{"id":828,"date":"2020-11-13T21:53:05","date_gmt":"2020-11-13T20:53:05","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=828"},"modified":"2020-11-13T21:53:05","modified_gmt":"2020-11-13T20:53:05","slug":"laurent-cappelletti","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2020\/11\/13\/laurent-cappelletti\/","title":{"rendered":"Laurent Cappelletti"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Laurent Cappelletti<\/strong> est dipl\u00f4m\u00e9 de l&#8217;EDHEC Business School et docteur HDR en sciences de gestion de l&#8217;Universit\u00e9 de Lyon. Il est <strong>professeur titulaire de la chaire Comptabilit\u00e9 et contr\u00f4le de gestion du Conservatoire national des arts et m\u00e9tiers<\/strong> dont il pr\u00e9side le Coll\u00e8ge des chaires. Il est chercheur au laboratoire de recherche LIRSA et directeur de programmes \u00e0 <strong>l\u2019institut ISEOR<\/strong>. Il est \u00e9galement coordinateur du r\u00e9seau de recherche international sur le management des <strong>normes T\u00e9tranormalisation<\/strong> et expert aupr\u00e8s de <strong>l\u2019Institut Sapiens<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Par ailleurs il est <strong>adjoint au maire<\/strong> de Mauguio-Carnon, au commerce et au d\u00e9veloppement num\u00e9rique et conseiller communautaire. Il a r\u00e9alis\u00e9 plus de 200 publications sur le contr\u00f4le de gestion, le management des normes, la gestion des politiques publiques et la recherche-intervention, r\u00e9compens\u00e9es \u00e0 deux reprises d\u2019un <em>best paper award<\/em> par <em>l&#8217;Academy of Management<\/em> (USA). Il \u00e9crit r\u00e9guli\u00e8rement des chroniques pour Le Monde, Les Echos, Le Figaro et l\u2019Opinion.<\/p>\n<p><span style=\"font-family: Montserrat; font-size: 12pt;\"><strong><u>Derni\u00e8res publications\u00a0:<br \/><\/u><\/strong><u>Ouvrage<\/u><\/span> :<br \/>2020. <em>La<\/em><span style=\"font-family: Montserrat; font-size: 12pt;\"><em> gestion innovante des normes<\/em>, avec N. Dufour, G\u00e9r\u00e9so \u00e9ditions.<br \/>2018. <\/span><span style=\"font-family: Montserrat; font-size: 12pt;\"><em>Intervention-Research<\/em>, avec A. Buono et H. Savall, I.A.P. Traduit en fran\u00e7ais\u00a0: La recherche-intervention, I.A.P.<\/span><\/p>\n<p><span style=\"font-family: Montserrat; font-size: 12pt;\"><u>Articles de revues scientifiques :<br \/><\/u><\/span><span style=\"font-family: Montserrat; font-size: 12pt;\">2020<em>. <\/em>L\u2019institutionnalisation des normes prudentielles. R\u00e9sultats d\u2019une recherche-intervention au sein d\u2019une mutuelle int\u00e9grant Solvabilit\u00e9 II,<em> Finance-Contr\u00f4le-Strat\u00e9gie, avec N. Dufour, \u00e0 para\u00eetre.<br \/><\/em><\/span><span style=\"font-family: Montserrat; font-size: 12pt;\">2019. Valorisation de la recherche par l\u2019exp\u00e9rimentation en entreprise. Cas du mod\u00e8le de management socio-\u00e9conomique, <em>Revue Fran\u00e7aise de Gestion<\/em>, avec H. Savall, V. Zardet et M. Bonnet, 7(284)\u00a0: 149-169.<\/span><\/p>\n<p><span style=\"font-family: Montserrat; font-size: 12pt;\"><u>Articles dans la presse nationale :<br \/><\/u><\/span><span style=\"font-family: Montserrat; font-size: 12pt;\">2020. Le co\u00fbt int\u00e9gral d\u2019un mois de confinement pourrait attendre jusqu\u2019\u00e0 150 milliards d\u2019euros, <em>Le Monde<\/em>, 3 avril.<br \/>2020. <\/span><span style=\"font-family: Montserrat; font-size: 12pt;\">L\u2019absent\u00e9isme au travail, un mal fran\u00e7ais gu\u00e9rissable, <em>Les Echos<\/em>, 26 novembre<\/span><\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Laurent Cappelletti est dipl\u00f4m\u00e9 de l&#8217;EDHEC Business School et docteur HDR en sciences de gestion de l&#8217;Universit\u00e9 de Lyon. Il est professeur titulaire de la chaire Comptabilit\u00e9 et contr\u00f4le de gestion du Conservatoire national des arts et m\u00e9tiers dont il pr\u00e9side le Coll\u00e8ge des chaires. Il est chercheur au laboratoire de recherche LIRSA et directeur &hellip; <\/p>\n","protected":false},"author":1,"featured_media":831,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/828"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=828"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media\/831"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}