{"id":698,"date":"2020-10-16T10:13:20","date_gmt":"2020-10-16T08:13:20","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=698"},"modified":"2020-10-16T10:13:20","modified_gmt":"2020-10-16T08:13:20","slug":"patrick-gosling","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2020\/10\/16\/patrick-gosling\/","title":{"rendered":"Patrick Gosling"},"content":{"rendered":"<p style=\"text-align: justify;\">Patrick Gosling est <strong>professeur \u00e9m\u00e9rite<\/strong> de <strong>psychologie sociale<\/strong> de l\u2019universit\u00e9 Paris Nanterre, membre du Laboratoire Parisien de Psychologie Sociale. Il travaille sur la <strong>th\u00e9orie de la dissonance cognitive<\/strong> et ses modes de r\u00e9duction, et \u00e9galement sur la <strong>discrimination<\/strong> ethnique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Patrick Gosling est professeur \u00e9m\u00e9rite de psychologie sociale de l\u2019universit\u00e9 Paris Nanterre, membre du Laboratoire Parisien de Psychologie Sociale. Il travaille sur la th\u00e9orie de la dissonance cognitive et ses modes de r\u00e9duction, et \u00e9galement sur la discrimination ethnique.<\/p>\n","protected":false},"author":1,"featured_media":699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/698"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=698"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media\/699"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}