{"id":687,"date":"2020-10-13T15:48:07","date_gmt":"2020-10-13T13:48:07","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=687"},"modified":"2020-10-13T15:48:07","modified_gmt":"2020-10-13T13:48:07","slug":"olivier-hirt","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2020\/10\/13\/olivier-hirt\/","title":{"rendered":"Olivier Hirt"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Olivier Hirt<\/strong> est <strong>Responsable du d\u00e9veloppement<\/strong> <strong>de la recherche \u00e0 l\u2019Ecole nationale sup\u00e9rieure de cr\u00e9ation industrielle (ENSCI les Ateliers)<\/strong>, membre du Centre de recherche en design (CRD, ENSCI &#8211; ENS Paris Saclay) et co-responsable pour l\u2019ENSCI de la Chaire innovation publique. Il est designer et titulaire du DEA \u201cConception de produits nouveaux et innovation\u201d de l\u2019ENSAM. Avant de rejoindre l\u2019ENSCI il a travaill\u00e9 chez Renault comme ing\u00e9nieur de recherche \u00e0 la Direction de la recherche et \u00e0 la Direction du design industriel, o\u00f9 il a pilot\u00e9 au c\u00f4t\u00e9 d\u2019Anne Asensio et avec les directions de l\u2019ing\u00e9nierie et du produit un chantier sur la place du design dans l\u2019organisation de la conception et de l\u2019innovation de Renault. Il a ensuite \u00e9t\u00e9 coordinateur op\u00e9rationnel au sein du GERPISA<strong> (ENS Paris Saclay)<\/strong> du projet europ\u00e9en ESEMK (European socio-\u00e9conomic models for a knowledge-based society, FP4, associant cinquante chercheurs et onze laboratoires dans quatre pays europ\u00e9ens, dont en France le CEPREMAP de l\u2019Ecole d\u2019\u00e9conomie de Paris, l\u2019EHESS, le CERNA et le CGS de Mines ParisTech, le CSU et l\u2019Universit\u00e9 de Bordeaux 4) sur le lien entre mod\u00e8les socio-\u00e9conomiques nationaux et mod\u00e8les d\u2019innovation des entreprises. A l\u2019ENSCI depuis 2008, il a \u00e9t\u00e9 responsable des enseignements de la formation initiale (o\u00f9 il a conduit en 2010-11 une refonte des enseignements), responsable du double cursus Sciences et design de l\u2019ENSCI avec Sorbonne universit\u00e9 et l\u2019Universit\u00e9 de Grenoble, et co-responsable du mast\u00e8re sp\u00e9cialis\u00e9 Innovation by design. Depuis 2015 il a pilot\u00e9 les partenariats de l\u2019ENSCI \u00e0 une dizaine de projets de recherche (ANR, DGE, europ\u00e9en), cr\u00e9\u00e9 en 2015 avec l\u2019ENS Paris Saclay et T\u00e9l\u00e9com ParisTech le master 2 Recherche en design,<\/p>\n<p style=\"text-align: justify;\"><strong>Il\u00a0 a d\u00e9velopp\u00e9 la Chaire innovation publique, co-port\u00e9e par l\u2019ENSCI, l\u2019ENA, Sciences Po et l\u2019Ecole polytechnique, et dont l\u2019Universit\u00e9 de Paris Est est partenaire du programme sur la th\u00e9matique droit et num\u00e9rique.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Olivier Hirt est Responsable du d\u00e9veloppement de la recherche \u00e0 l\u2019Ecole nationale sup\u00e9rieure de cr\u00e9ation industrielle (ENSCI les Ateliers), membre du Centre de recherche en design (CRD, ENSCI &#8211; ENS Paris Saclay) et co-responsable pour l\u2019ENSCI de la Chaire innovation publique. Il est designer et titulaire du DEA \u201cConception de produits nouveaux et innovation\u201d de &hellip; <\/p>\n","protected":false},"author":1,"featured_media":685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/687"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=687"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/687\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media\/685"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}