{"id":4276,"date":"2022-02-07T14:23:51","date_gmt":"2022-02-07T13:23:51","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=4276"},"modified":"2022-02-07T14:23:51","modified_gmt":"2022-02-07T13:23:51","slug":"sylvie-gerbaix","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2022\/02\/07\/sylvie-gerbaix\/","title":{"rendered":"Sylvie Gerbaix"},"content":{"rendered":"<p style=\"text-align: justify;\">Sylvie GERBAIX, est <strong>enseignant-chercheur<\/strong> \u00e0 l\u2019Universit\u00e9 d\u2019Aix-Marseille et \u00e0 l\u2019Universit\u00e9 de Montpellier.<\/p>\n<p style=\"text-align: justify;\">Dipl\u00f4m\u00e9e HEC-JF, Agr\u00e9g\u00e9e d\u2019Economie et Gestion, titulaire d\u2019un doctorat en Sciences de Gestion et d\u2019une Habilitation \u00e0 diriger des recherches.<strong> Ses travaux en syst\u00e8mes d\u2019information et de communication<\/strong>, rel\u00e8vent de plusieurs domaines d\u2019application tels que : la visioconf\u00e9rence, l\u2019enseignement \u00e0 distance, la logistique humanitaire, la sant\u00e9, la t\u00e9l\u00e9m\u00e9decine, les syst\u00e8mes algorithmiques et \u00ab l\u2019intelligence artificielle \u00bb, et les syst\u00e8mes d\u2019information des organisations. Ses travaux de recherche, articles et ouvrages, visent \u00e0 une <strong>meilleure compr\u00e9hension de la dynamique d\u2019\u00e9mergence organisationnelle des syst\u00e8mes d\u2019information et de communication<\/strong>, de leur \u00e9valuation, de leurs implications, de leurs enjeux et de leurs risques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sylvie GERBAIX, est enseignant-chercheur \u00e0 l\u2019Universit\u00e9 d\u2019Aix-Marseille et \u00e0 l\u2019Universit\u00e9 de Montpellier. Dipl\u00f4m\u00e9e HEC-JF, Agr\u00e9g\u00e9e d\u2019Economie et Gestion, titulaire d\u2019un doctorat en Sciences de Gestion et d\u2019une Habilitation \u00e0 diriger des recherches. Ses travaux en syst\u00e8mes d\u2019information et de communication, rel\u00e8vent de plusieurs domaines d\u2019application tels que : la visioconf\u00e9rence, l\u2019enseignement \u00e0 distance, la logistique &hellip; <\/p>\n","protected":false},"author":1,"featured_media":4277,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/4276"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=4276"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/4276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=4276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=4276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=4276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}