{"id":3882,"date":"2022-01-05T14:54:05","date_gmt":"2022-01-05T13:54:05","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=3882"},"modified":"2022-01-05T14:54:05","modified_gmt":"2022-01-05T13:54:05","slug":"loi-des-quotas-bilan-et-perspectives","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2022\/01\/05\/loi-des-quotas-bilan-et-perspectives\/","title":{"rendered":"Loi des quotas : bilan et perspectives"},"content":{"rendered":"<p style=\"text-align: justify;\">Fin d\u00e9cembre 2021,<span style=\"color: #000000;\"><a href=\"https:\/\/www.vie-publique.fr\/loi\/278858-parite-loi-rixain-24-dec-2021-egalite-professionnelle-femmes-hommes\"> la proposition de loi, port\u00e9 par la d\u00e9put\u00e9e Marie-Pierre Rixain<\/a> a \u00e9t\u00e9 adopt\u00e9e. Il y a d\u00e9sormais obligation d\u2019avoir, pour les entreprises d\u2019au moins 1000 salari\u00e9s, un quota de repr\u00e9sentation de chaque sexe parmi les cadres dirigeants et les membres des instances dirigeantes des entreprises d\u2019au moins 1.000 salari\u00e9s\u00a0:\u00a0au moins 30\u00a0% de femmes en 2027, et 40 % en 2030. Les entreprises \u00ab\u00a0hors la loi\u00a0\u00bb devraient verser une amende \u00e9gale \u00e0 1% de la masse salariale. Ce texte doit permettre aux femmes de p\u00e9n\u00e9trer au sein m\u00eame du vrai pouvoir \u00e9conomique.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cette loi est dans la lign\u00e9e de la <a href=\"https:\/\/travail-emploi.gouv.fr\/actualites\/l-actualite-du-ministere\/article\/egalite-professionnelle-10-ans-de-la-loi-cope-zimmermann\">loi Cop\u00e9-Zimmermann<\/a> qui en 2011 a impos\u00e9 des quotas de femmes dans les conseils d&#8217;administration<a style=\"color: #000000;\" href=\"#_ftn1\" name=\"_ftnref1\"><sup>[1]<\/sup><\/a>. Cette loi a conduit la France \u00e0 la premi\u00e8re place en mati\u00e8re de f\u00e9minisation des conseils d&#8217;administration tout juste devant la Norv\u00e8ge qui a choisi d\u00e8s 2003 de mettre en place des quotas.\u00a0 Les femmes occupent 45,8 % des postes\u00a0d&#8217;administrateur, contre 12,5 %, en 2010. Sodexo, Kering, Ipsos ou CGG\u00a0sont au-dessus de 60%. Mais la loi Cop\u00e9-Zimmermann n&#8217;a pas ruissel\u00e9 sur les comit\u00e9s de direction qui restent encore tr\u00e8s masculins. Les femmes ne repr\u00e9sentent\u00a0que 22 % de leurs effectifs au sein du SBF 120, contre 7 % en 2009.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Cette nouvelle loi doit se regarder \u00e0 l\u2019aune de la loi Cop\u00e9-Zimmerman et de ses cons\u00e9quences sur les comportements des entreprises. Dans un travail r\u00e9cent (Ossiba et S\u00e9verin, 2017) ont \u00e9tudi\u00e9s l\u2019impact de la f\u00e9minisation sur le contr\u00f4le de la qualit\u00e9 de l\u2019information financi\u00e8re au travers de la manipulation des r\u00e9sultats comptables. Sur un \u00e9chantillon de 143 firmes cot\u00e9es sur Euronext entre 2011 (date de promulgation de la loi Cop\u00e9-Zimmerman) et 2017 (date de l\u2019obligation d\u2019un quota de 40% de femmes dans les conseils), les r\u00e9sultats montrent des r\u00e9sultats instructifs. Si l\u2019augmentation de la pr\u00e9sence des femmes a conduit \u00e0 une am\u00e9lioration g\u00e9n\u00e9rale de la qualit\u00e9 des \u00e9tats comptables, il n\u2019en reste pas moins que derri\u00e8re ce r\u00e9sultat se cache une r\u00e9alit\u00e9 plus contrast\u00e9e. En distinguant deux types de firmes (affect\u00e9es et non affect\u00e9es)<a style=\"color: #000000;\" href=\"#_ftn2\" name=\"_ftnref2\"><sup>[2]<\/sup><\/a>, l\u2019\u00e9tude met en \u00e9vidence que les entreprises affect\u00e9es ont vu une d\u00e9gradation de la qualit\u00e9 de l\u2019information financi\u00e8re en 2014 au contraire des entreprises non affect\u00e9es. En revanche, la qualit\u00e9 de l\u2019information des entreprises affect\u00e9es gagne en qualit\u00e9 en 2017, date de l\u2019obligation d\u2019un quota de 40% de femmes au sein des conseils.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Comment alors expliquer ce r\u00e9sultat\u00a0? Premi\u00e8rement en raison du r\u00f4le encore pr\u00e9gnant de la femme au sein de la vie domestique. Les femmes qu\u2019elles soient aux 39 H ou aux 35 H consacrent de plus en plus de temps \u00e0 leurs enfants. Cette tendance en hausse montre que le temps suppl\u00e9mentaire est r\u00e9affect\u00e9 \u00e0 du temps de qualit\u00e9 plut\u00f4t qu&#8217;\u00e0 des t\u00e2ches domestiques plus monotones. Deuxi\u00e8mement, les quotas bousculent les habitudes des hommes. Ces derniers sont oblig\u00e9s de changer de strat\u00e9gie. Ils doivent aller chercher, dans des r\u00e9seaux qui ne leur sont pas familiers, des femmes pour se conformer \u00e0 la loi.\u00a0<a href=\"https:\/\/www.lesechos.fr\/2018\/09\/comment-les-conseils-dadministration-du-cac-40-se-sont-transformes-977656\">Au final, cette diversit\u00e9 peut avoir des effets positifs<\/a> mais ces effets ne sont pas imm\u00e9diats. En effet, toute activit\u00e9 n\u00e9cessite de l\u2019exp\u00e9rience et ce n\u2019est qu\u2019apr\u00e8s un certain temps d\u2019apprentissage que l\u2019on peut mesurer les effets positifs ou n\u00e9gatifs des nouveaux entrants.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Des \u00e9tudes acad\u00e9miques (Ye et al., 2010) ne parviennent pas \u00e0 trouver une influence positive des femmes directrices sur la qualit\u00e9 de l\u2019information; les auteurs expliquent leurs r\u00e9sultats en citant une \u00e9tude de McKinsey &amp; Company de 2007 qui montre que les femmes sont confront\u00e9es \u00e0 plusieurs obstacles, tels que : l&#8217;occupation (\u00e9quilibre entre le travail et les responsabilit\u00e9s domestiques), les probl\u00e8mes de l\u00e9gitimit\u00e9 (efforts n\u00e9cessaires pour \u00eatre reconnues) et diverses perceptions sociologiques qui entravent leur r\u00e9ussite. Cependant, des attentes diff\u00e9rentes en mati\u00e8re de r\u00f4le social peuvent \u00e9galement expliquer ce r\u00e9sultat, et le tokenisme peut \u00eatre une cause des relations n\u00e9gatives entre les femmes administrateurs et la qualit\u00e9 de l\u2019information comptable) si les femmes administrateurs sont choisies par les entreprises uniquement pour satisfaire les pressions sociales plut\u00f4t que pour r\u00e9pondre aux besoins r\u00e9els des entreprises (Garc\u00eda Lara et al., 2017; Srinidhi et al., 2011).<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Au-del\u00e0 de ces explications, il faut donc se monter prudent sur les <a href=\"https:\/\/www.oecd.org\/fr\/social\/quotas-egalite-hommes-femmes.htm\">impacts des quotas<\/a> car ceux-ci peuvent \u00eatres sources d\u2019avantages et d\u2019inconv\u00e9nients. En effet, les effets r\u00e9els de la l\u00e9gislation obligatoire sur le genre ont \u00e9t\u00e9 critiqu\u00e9s (Bender et al., 2016). Les adh\u00e9rents anti-quotas affirment que les quotas de genre \u00e9vincent les autres minorit\u00e9s, encouragent la promotion de femmes administrateurs inexp\u00e9riment\u00e9es (Pande et Ford, 2011), et interf\u00e8rent avec le processus de nomination directe en r\u00e9duisant les droits des actionnaires \u00e0 nommer librement les administrateurs (Bender et al., 2015). \u00c0 l&#8217;inverse, les pro-quotas accueillent favorablement ce type de l\u00e9gislation, soutenant que les femmes administrateurs apportent des viviers de comp\u00e9tences compl\u00e9mentaires \u00e0 ceux des hommes (Bender et al., 2015) et que les entreprises qui privent leur conseil de femmes peuvent \u00eatre d\u00e9savantag\u00e9es par rapport aux entreprises qui incluent des femmes.<\/span><\/p>\n<p style=\"text-align: right;\"><span style=\"color: #000000;\"><a style=\"color: #000000; text-decoration: underline;\" href=\"http:\/\/observatoire-asap.org\/index.php\/2022\/01\/05\/husserl-ossiba\/\"><strong>Husserl Ossiba<\/strong><\/a>, <strong><a style=\"color: #000000; text-decoration: underline;\" href=\"https:\/\/observatoire-asap.org\/index.php\/2021\/04\/07\/eric-severin\/\">Eric S\u00e9verin<\/a><\/strong><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> La loi Cop\u00e9-Zimmerman, comme celle port\u00e9e par Marie-Pierre Rixain, obligeait les entreprises \u00e0 porter le nombre d\u2019administrateurs femmes \u00e0 20% en 2014 et 40% en 2017.<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Une entreprise non affect\u00e9e est une entreprise qui avant l\u2019obligation d\u2019au moins 20% de femmes avant 2014 et d\u2019au moins 40% avant 2017 avait un pourcentage de femmes proche des seuils l\u00e9gaux. Les entreprises affect\u00e9es sont celles dont le pourcentage de femmes \u00e9tat tr\u00e8s \u00e9loign\u00e9 du seuil l\u00e9gal.<\/p>\n<p><strong>R\u00e9f\u00e9rences<\/strong><\/p>\n<p style=\"text-align: justify;\">Au total, le l\u00e9gislateur devrait pouvoir tirer des premiers effets de la loi Cop\u00e9-Zimmermann des \u00e9l\u00e9ments de r\u00e9flexion sur les cons\u00e9quences \u00e0 venir de la loi Rixain.<\/p>\n<p style=\"text-align: justify;\">Bender, A. F., Berrebi-Hoffmann, I., &amp; Reign\u00e9, P. (2015). Les quotas de femmes dans les conseils d\u2019administration.\u00a0<em>Travail, genre et soci\u00e9t\u00e9s<\/em>, <em>2<\/em>, 169-173.<\/p>\n<p style=\"text-align: justify;\">Bender, A. F., Dang, R., &amp; Scotto, M. J. (2016). Les profils des femmes membres des conseils d\u2019administration en France.\u00a0<em>Travail, genre et soci\u00e9t\u00e9s<\/em>, <em>1<\/em>, 67-85.<\/p>\n<p style=\"text-align: justify;\">Garc\u00eda Lara, J. M., Garc\u00eda Osma, B., Mora, A., &amp; Scapin, M. (2017). The monitoring role of female directors over accounting quality. <em>Journal of Corporate Finance<\/em>, <em>45<\/em>, 651-668.<\/p>\n<p style=\"text-align: justify;\">McKinsey and Company. (2007). Women matter: gender diversity. a corporate performance driver note that although the analysis did not show a causal link, this research clearly argues for greater gender diversity among corporate leaders.<\/p>\n<p style=\"text-align: justify;\">Ossiba, H., &amp; S\u00e9verin, E. (2020). Board gender diversity and earings quality: Evidence from a gender quota in France, <em>Congr\u00e8s de l\u2019Association Internationale de Gouvernance (AIG)<\/em>, Clermont Ferrand, d\u00e9cembre.<\/p>\n<p style=\"text-align: justify;\">Pande, R. &amp; Ford, D. (2011). Gender quotas and female leadership: A review. Background paper for the World Development Report.<\/p>\n<p style=\"text-align: justify;\">Srinidhi, B., Gul, F. A., &amp; Tsui, J. (2011). Female directors and earnings quality.\u00a0<em>Contemporary\u00a0 Accounting Research<\/em>,\u00a0<em>28<\/em>(5), 1610-1644.<\/p>\n<p style=\"text-align: justify;\">Ye, K., Zhang, R., &amp; Rezaee, Z. (2010). Does top executive gender diversity affect earnings quality? A large sample analysis of Chinese listed firms<em>. Advances in Accounting<\/em>, <em>26<\/em>(1), 47-54.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fin d\u00e9cembre 2021, la proposition de loi, port\u00e9 par la d\u00e9put\u00e9e Marie-Pierre Rixain a \u00e9t\u00e9 adopt\u00e9e. Il y a d\u00e9sormais obligation d\u2019avoir, pour les entreprises d\u2019au moins 1000 salari\u00e9s, un quota de repr\u00e9sentation de chaque sexe parmi les cadres dirigeants et les membres des instances dirigeantes des entreprises d\u2019au moins 1.000 salari\u00e9s\u00a0:\u00a0au moins 30\u00a0% de &hellip; <\/p>\n","protected":false},"author":1,"featured_media":3883,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[64],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3882"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3882"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3882\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}