{"id":3647,"date":"2021-09-23T10:50:17","date_gmt":"2021-09-23T08:50:17","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=3647"},"modified":"2021-09-23T10:50:17","modified_gmt":"2021-09-23T08:50:17","slug":"tiers-lieux-a-la-rencontre-de-laction-publique-et-de-laction-privee","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/09\/23\/tiers-lieux-a-la-rencontre-de-laction-publique-et-de-laction-privee\/","title":{"rendered":"Tiers lieux : \u00e0 la rencontre de l&#8217;action publique et de l&#8217;action priv\u00e9e"},"content":{"rendered":"<p style=\"text-align: justify;\">Bien souvent les habitants sont consid\u00e9r\u00e9s comme les \u00ab&nbsp;cibles&nbsp;\u00bb des politiques publiques. Rappelons qu\u2019une cible c\u2019est \u00ab&nbsp;ce qui est vis\u00e9 lors d\u2019une attaque&nbsp;\u00bb. Parfois le raisonnement militaire est doubl\u00e9 d\u2019un raisonnement marketing et les cibles sont alors segment\u00e9es jusqu\u2019aux non-usagers c\u2019est-\u00e0-dire aux habitants incapables de faire valoir leur droit&nbsp;: les invisibles. Les exclus finissent par \u00eatre perdus de vue des radars. \u00ab&nbsp;L\u2019intention sur autrui&nbsp;\u00bb est un travers des politiques publiques qui consid\u00e8rent l\u2019autre comme un mineur auquel il s\u2019agit d\u2019apporter des services, de l\u2019aide ou de la protection. C\u2019est \u00e0 la fois confortable et infantilisant. Confortable, quand, sans le demander chacun obtient des services. Infantilisant, car tel d\u00e9cideur politique vient vite \u00e0 stigmatiser un individu en lui indiquant par exemple qu\u2019il n\u2019a qu\u2019\u00e0 traverser la rue pour trouver du travail, faisant fi de la vie de l\u2019individu, de ses aspirations et de ses engagements sociaux. Ne pas suivre le conseil \u00e9quivalant rapidement \u00e0 un jugement moral du type le ch\u00f4mage est de la responsabilit\u00e9 de cet individu r\u00e9calcitrant refusant l\u2019aide offerte, ou bien version plus douce, mais tout aussi d\u00e9l\u00e9t\u00e8re \u00ab&nbsp;nous n\u2019avons pas su faire preuve de p\u00e9dagogie pour expliquer notre politique&nbsp;\u00bb. Le recours \u00e0 \u00ab&nbsp;l\u2019argument p\u00e9dagogique&nbsp;\u00bb \u00e9tant au passage le t\u00e9moignage d\u2019une confusion entre propagande et p\u00e9dagogie. La p\u00e9dagogie laisse l\u2019individu libre d\u2019agir et de d\u00e9velopper son potentiel. Le faux message de contrition d\u2019un ministre, d\u2019un m\u00e9decin, d\u2019un d\u00e9cideur politique expliquant qu\u2019il a manqu\u00e9 de p\u00e9dagogie continue de le mettre en posture haute de l\u2019action. Cela continue aussi \u00e0 agacer les p\u00e9dagogues qui savent que le mouvement juste n\u2019est pas forc\u00e9 mais accompagn\u00e9.<\/p>\n<p style=\"text-align: justify;\"><strong>Et si les tiers lieux \u00e9taient une opportunit\u00e9 de proposer une autre p\u00e9dagogie politique&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify;\">Les <a href=\"https:\/\/connectedbynature.org\/?page_id=903\">tiers lieux<\/a> sont embl\u00e9matiques de la fa\u00e7on dont les pouvoirs publics appr\u00e9hendent les territoires et renouvellent leur fa\u00e7on d\u2019appr\u00e9hender les populations, en partant un peu plus des initiatives d\u2019individus moteurs (culturels cr\u00e9atifs, militants, entrepreneurs passionn\u00e9s etc.). Les pouvoirs publics prendraient plus en consid\u00e9ration un ph\u00e9nom\u00e8ne de vitalisation des espaces en proximit\u00e9 nomm\u00e9s \u00ab tiers lieux \u00bb. Dans un pays comme la France, il y aurait 1800 tiers lieux recens\u00e9s en 2018. Pour le coup, les tiers lieux offrent un espace p\u00e9dagogique d\u2019exp\u00e9rimentation incomparable. Ils sont faiblement d\u00e9finis, prot\u00e9iformes, \u00ab hors programme \u00bb, assez insaisissables et n\u00e9cessitent une invention locale pour s\u2019inscrire dans un tissu social. L\u2019une de leur caract\u00e9ristique pourrait bien \u00eatre la dimension communautaire, la forte envie d\u2019entreprendre, d\u2019innover et in fine d\u2019apprendre ensemble parce que mon voisin, la cause ou le lieu mis en avant ont du sens. Tout se passe comme si cet objet mal d\u00e9fini \u00e9tait une occasion de dialogue de proximit\u00e9 m\u00ealant int\u00e9r\u00eat public et priv\u00e9, obligeant \u00e0 reconsid\u00e9rer les certitudes pour faire face \u00e0 l\u2019\u00e9nergie de collectifs qui entendent s\u2019exprimer. Voil\u00e0 une forme de p\u00e9dagogie o\u00f9&nbsp; <a href=\"https:\/\/journals.openedition.org\/sociologies\/642\">l&#8217;engagement<\/a> peut se cr\u00e9er au service de l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral, plut\u00f4t qu\u2019une injonction enrob\u00e9e \u00e0 faire ce qui est attendu.<\/p>\n<p style=\"text-align: justify;\">L\u2019\u00e9tat Fran\u00e7ais observe le ph\u00e9nom\u00e8ne et l\u2019accompagne, certains diront timidement au regard des enjeux de coh\u00e9sion sociale et de lutte contre la paup\u00e9risation des territoires ruraux ou enclav\u00e9s dans le but de&nbsp;:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Favoriser le maillage le plus fin possible des territoires en tiers-lieux ;<\/li>\n<li>Donner les moyens aux tiers-lieux de diversifier leurs revenus en d\u00e9veloppant des services d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral d\u00e9clin\u00e9s en fonction des besoins des territoires ;<\/li>\n<li>Faciliter la professionnalisation et l\u2019organisation des r\u00e9seaux de tiers-lieux ;<\/li>\n<li>Impliquer des partenaires publics et priv\u00e9s autour de ce programme en proposant un cadre d\u2019intervention commun et des outils mutualis\u00e9s.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Le raisonnement qui sous-tend cet appui pourrait \u00eatre \u00ab&nbsp;puisque les politiques publiques achoppent \u00e0 cr\u00e9er du lien social et de la valeur commune sur les territoires, laissons les initiatives grandir, accompagnons les porteurs de projets qui sauront mieux porter des enjeux locaux, plut\u00f4t qu\u2019une politique globale, d\u00e9cid\u00e9e de fa\u00e7on centralis\u00e9e qui finit par se d\u00e9ployer de fa\u00e7on compl\u00e9tement d\u00e9sincarn\u00e9e&nbsp;\u00bb.<\/p>\n<p style=\"text-align: justify;\">Le moteur de cette dynamique est \u00ab&nbsp;d\u2019apprendre ensemble&nbsp;\u00bb, c\u2019est au c\u0153ur des \u00ab&nbsp;<a href=\"https:\/\/www.centre-inffo.fr\/innovation-formation\/articles\/les-territoires-apprenants-une-approche-ecologique-de-la-formation-denis-cristol-2-2\">territoires apprenants<\/a> \u00bb, territoire de projet plut\u00f4t que seulement territoires dot\u00e9s de ressources. Il y a l\u00e0 mati\u00e8re \u00e0 promouvoir de nombreuses mani\u00e8res de favoriser cet apprendre, entreprendre et innover ensemble en promouvant les cercles d\u2019apprentissage et de dialogue, les communaut\u00e9s apprenantes, les savoir faire des facilitateurs en intelligence collective, les r\u00e9seaux d\u2019\u00e9change de savoir, les formes de recherche interdisciplinaires, les projets collaboratifs, l\u2019\u00e9criture collaborative, les festivals de l\u2019apprendre.<\/p>\n<p style=\"text-align: justify;\">Mettons de l\u2019\u00e9nergie et des budgets dans cette direction nous r\u00e9colterons collectivement des communs, commen\u00e7ons par activer les friches industrielles, postales, militaires, agricoles. Tous les espaces d\u00e9laiss\u00e9s peuvent devenir les pistes d\u2019envol d\u2019id\u00e9es et de groupes r\u00e9g\u00e9n\u00e9rateurs des territoires.<\/p>\n<p style=\"text-align: right;\">&nbsp;<a href=\"http:\/\/observatoire-asap.org\/index.php\/2020\/11\/24\/denis-cristol\/\"><strong>Denis Cristol<\/strong><\/a><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>R\u00e9f\u00e9rences<\/strong><\/p>\n<p style=\"text-align: justify;\">Territoire.gouv Tiers lieux: <a href=\"https:\/\/www.cohesion-territoires.gouv.fr\/tiers-lieux\">https:\/\/www.cohesion-territoires.gouv.fr\/tiers-lieux<\/a><\/p>\n<p style=\"text-align: justify;\">Faire ensemble pour mieux vivre ensemble. Mission coworking territoire: <a href=\"Https:\/\/www.vie-publique.fr\/rapport\/37656-faire-ensemble-pour-mieux-vivre-ensemble-mission-coworking-territoires\">Https:\/\/www.vie-publique.fr\/rapport\/37656-faire-ensemble-pour-mieux-vivre-ensemble-mission-coworking-territoires<\/a><\/p>\n<p style=\"text-align: justify;\">Festival de l\u2019apprendre. Les tiers lieux faire ensemble pour apprendre ensemble: <a href=\"https:\/\/www.festivaldelapprendre.fr\/pro-les-tiers-lieux-faire-ensemble-pour-apprendre-ensemble\/\">https:\/\/www.festivaldelapprendre.fr\/pro-les-tiers-lieux-faire-ensemble-pour-apprendre-ensemble\/<\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.centre-inffo.fr\/innovation-formation\/articles\/les-territoires-apprenants-une-approche-ecologique-de-la-formation-denis-cristol-2-2\">Les territoires apprenants&nbsp;: une approche \u00e9cologique de la formation (Denis Cristol, 2\/2) &#8211; Centre Inffo (centre-inffo.fr)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bien souvent les habitants sont consid\u00e9r\u00e9s comme les \u00ab&nbsp;cibles&nbsp;\u00bb des politiques publiques. Rappelons qu\u2019une cible c\u2019est \u00ab&nbsp;ce qui est vis\u00e9 lors d\u2019une attaque&nbsp;\u00bb. Parfois le raisonnement militaire est doubl\u00e9 d\u2019un raisonnement marketing et les cibles sont alors segment\u00e9es jusqu\u2019aux non-usagers c\u2019est-\u00e0-dire aux habitants incapables de faire valoir leur droit&nbsp;: les invisibles. Les exclus finissent par &hellip; <\/p>\n","protected":false},"author":1,"featured_media":2099,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[64],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3647"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3647"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3647\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media\/2099"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}