{"id":3465,"date":"2021-07-05T10:34:28","date_gmt":"2021-07-05T08:34:28","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=3465"},"modified":"2021-07-05T10:34:28","modified_gmt":"2021-07-05T08:34:28","slug":"la-theorie-de-lacceptabilite-est-elle-acceptable","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/07\/05\/la-theorie-de-lacceptabilite-est-elle-acceptable\/","title":{"rendered":"La th\u00e9orie de l\u2019acceptabilit\u00e9 est-elle acceptable ?"},"content":{"rendered":"<p style=\"text-align: justify;\">Dans un livre fameux paru en 1887, <a href=\"https:\/\/fr.wikipedia.org\/wiki\/G\u00e9n\u00e9alogie_de_la_morale\"><em>La g\u00e9n\u00e9alogie de la morale<\/em><\/a>, Nietzsche s\u2019interroge sur la notion de valeur dans les termes suivants\u00a0: au fond, quelle est la valeur de la valeur\u00a0? Si la valeur correspond au r\u00e9sultat d\u2019une \u00e9valuation, peut-on en quelque sorte \u00e9valuer l\u2019\u00e9valuation\u00a0? Un tel redoublement du questionnement, qui est le propre de la r\u00e9flexivit\u00e9, m\u00e8nera le philosophe \u00e0 distinguer le ressentiment de l\u2019acquiescement \u00e0 la vie.<\/p>\n<p style=\"text-align: justify;\">Cette d\u00e9marche me para\u00eet \u00e0 bien des \u00e9gards prometteuse, en premier lieu pour interroger tous les concepts des sciences humaines en g\u00e9n\u00e9ral, et des sciences de l\u2019organisation en particulier, qui tendent \u00e0 rev\u00eatir une port\u00e9e m\u00e9diatico-politique d\u00e9passant de loin leur seule utilisation analytique. Ce qui revient \u00e0 sonder la nouveaut\u00e9 du nouveau, ou encore la mod\u00e9it\u00e9 de la mode.<\/p>\n<p style=\"text-align: justify;\">Ainsi en va-t-il de l\u2019acceptabilit\u00e9 sociale <a href=\"http:\/\/observatoire-asap.org\/index.php\/2020\/12\/19\/la-majorite-silencieuse-nen-veut-pas\/\">dont l\u2019emploi ne laisse pas de cro\u00eetre parmi les d\u00e9cideurs de l\u2019action publique<\/a>. S\u2019agit-il de promulguer une loi dont les mesures risquent, selon les sondages d\u2019opinion, de provoquer le m\u00e9contentement, la frustration voire l\u2019ire des citoyens\u00a0? Derechef se trouve appel\u00e9e, \u00e0 la rescousse, telle une h\u00e9ro\u00efne ou un <a href=\"http:\/\/observatoire-asap.org\/index.php\/2020\/10\/24\/lacceptabilite-sociale-le-nouvel-eldorado-de-laction-publique\/\">nouvel Eldorado<\/a>, l\u2019acceptabilit\u00e9 sociale dot\u00e9e de tous les pouvoirs, par\u00e9e de toutes les vertus. Un tel succ\u00e8s me m\u00e8ne \u00e0 r\u00e9p\u00e9ter la question g\u00e9n\u00e9alogique nietzsch\u00e9enne\u00a0: la th\u00e9orie de l\u2019acceptabilit\u00e9 est-elle acceptable\u00a0? Ou, mieux encore\u00a0: la th\u00e9orie de l\u2019acceptabilit\u00e9 sociale est-elle politiquement acceptable\u00a0?<\/p>\n<p style=\"text-align: justify;\">Mais avant de r\u00e9pondre \u00e0 cette question, je souhaite pr\u00e9ciser que j\u2019entends ici l\u2019acceptabilit\u00e9 sociale dans un sens large, comme englobant d\u2019une part \u00ab\u00a0les repr\u00e9sentations des personnes face \u00e0 une technologie future ou possible\u00a0\u00bb et d\u2019autre part \u00ab\u00a0le v\u00e9cu des personnes lors et suite \u00e0 l\u2019introduction des TIC\u00a0\u00bb (Bobillier-Chaumon et Dubois, 2009, p. 356), ce deuxi\u00e8me aspect se rapprochant sensiblement de ce que les sciences de gestion nomment alors \u00ab\u00a0processus d\u2019appropriation\u00a0\u00bb. L\u2019acceptabilit\u00e9 comprend aussi bien l\u2019\u00e9tude du syst\u00e8me et de ses caract\u00e9ristiques (et notamment la facilit\u00e9 d\u2019utilisation et l\u2019efficacit\u00e9) que l\u2019observation des comportements individuels et sociaux (Dubois et Bobillier-Chaumon, 2009).<\/p>\n<p style=\"text-align: justify;\">\u00c0 la question pos\u00e9e\u00a0: \u00ab\u00a0L\u2019acceptabilit\u00e9 sociale est-elle politiquement acceptable\u00a0?\u00a0\u00bb, je r\u00e9ponds par la n\u00e9gative et justifie mon propos en avan\u00e7ant la th\u00e8se que l\u2019acceptabilit\u00e9 sociale est ce qui reste de la l\u00e9gitimit\u00e9 apr\u00e8s la mort du politique. Je me rapproche de la sorte des analyses de Pierre-Louis Mayaux (2015, p. 257) qui formule quant \u00e0 lui \u00ab\u00a0l\u2019hypoth\u00e8se g\u00e9n\u00e9rale selon laquelle l\u2019acceptabilit\u00e9 serait \u00e0 la postd\u00e9mocratie ce que la l\u00e9gitimit\u00e9 est \u00e0 la d\u00e9mocratie\u00a0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Je ne pose donc pas de synonymie entre les deux termes d\u2019\u00a0\u00ab\u00a0acceptabilit\u00e9\u00a0\u00bb et de \u00ab\u00a0l\u00e9gitimit\u00e9\u00a0\u00bb, \u00e0 l\u2019encontre de ce qu\u2019avan\u00e7ait Romain Laufer dans son article s\u00e9minal de 1984\u00a0; en revanche, je m\u2019inspire fortement du raisonnement de ce dernier afin d\u2019exposer notre th\u00e8se. Lisons plut\u00f4t\u00a0: \u00ab\u00a0Soit une action, de deux choses l\u2019une, ou bien tout se passe bien [\u2026] et il n\u2019y a alors rien \u00e0 dire ou bien quelqu\u2019un proteste [\u2026], dans ce cas il s\u2019adresse \u00e0 celui qui vient d\u2019agir [\u2026] pour lui demander\u00a0: au nom de quoi as-tu agi\u00a0? Celui-ci doit alors r\u00e9pondre, et il r\u00e9pondra par un discours\u00a0: ce discours constitue son syst\u00e8me de l\u00e9gitimit\u00e9\u00a0\u00bb (Laufer, 1984, p. 53)<\/p>\n<p style=\"text-align: justify;\">Romain Laufer lie \u00e0 juste titre la l\u00e9gitimit\u00e9 \u00e0 un \u00ab\u00a0au nom de\u00a0\u00bb\u00a0: \u00e0 un Tiers ext\u00e9rieur au syst\u00e8me qui lui sert de garant, \u00e0 une fiction fondatrice (et donc arbitraire) capable de donner une r\u00e9ponse \u00e0 toutes les questions que se posent les membres de la communaut\u00e9, et dont le message est relay\u00e9 par des institutions. De ce point de vue, qui rejoint celui de <a href=\"https:\/\/arsdogmatica.com\/\">l\u2019anthropologie dogmatique de Pierre Legendre<\/a>, le politique n\u2019est autre que la voix et la mise en sc\u00e8ne symbolique de ce Tiers garant.<\/p>\n<p style=\"text-align: justify;\">Or, \u00e0 l\u2019\u00e9poque de la fin des grands r\u00e9cits modernes, \u00e0 l\u2019\u00e9poque de l\u2019essoufflement des institutions menac\u00e9es de rompre sous le joug de la logique \u00e9conomique capitaliste mondiale, tant le r\u00e9cit fondateur que ses porte-paroles ne peuvent plus faire entendre leur voix et l\u00e9gitimer l\u2019action publique. Demeure alors possible le d\u00e9port du politique vers les sciences humaines et sociales\u00a0: c\u2019est l\u2019\u00e8re de la fabrique scientifique du comportement attendu, dont l\u2019acceptabilit\u00e9 sociale n\u2019est assur\u00e9ment que l\u2019un des noms.<\/p>\n<p style=\"text-align: right;\"><a href=\"http:\/\/observatoire-asap.org\/index.php\/2020\/11\/17\/baptiste-rappin\/\">Baptiste Rappin<\/a><\/p>\n<p><strong>R\u00e9f\u00e9rences<\/strong><\/p>\n<p>Bobillier-Chaumon M-E,\u00a0 Dubois M. (2009), \u00ab L\u2019adoption des technologies en situation professionnelle : quelles articulations possibles entre acceptabilit\u00e9 et acceptation ? \u00bb, <em>Le travail humain<\/em>, vol. 72, p. 355-382.<\/p>\n<p>Dubois M., Bobillier-Chaumon M-E.\u00a0 (2009), \u00ab L\u2019acceptabilit\u00e9 des technologies : bilans et nouvelles perspectives \u00bb, <em>Le travail humain<\/em>, vol. 72, p. 305-310.<\/p>\n<p>Laufer R. (1984), \u00ab L\u2019acceptabilit\u00e9 sociale : une probl\u00e9matique \u00bb, <em>Revue Fran\u00e7aise de Gestion<\/em>, juin-juillet-ao\u00fbt,\u00a0 p. 52-60.<\/p>\n<p>Mayaux P-L. (2015), \u00ab La production de l\u2019acceptabilit\u00e9 sociale. Privatisation des services d\u2019eau et normes sociales d\u2019acc\u00e8s en Am\u00e9rique latine \u00bb, <em>Revue Fran\u00e7aise de Science Politique<\/em>, vol. 65, p. 237-259.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans un livre fameux paru en 1887, La g\u00e9n\u00e9alogie de la morale, Nietzsche s\u2019interroge sur la notion de valeur dans les termes suivants\u00a0: au fond, quelle est la valeur de la valeur\u00a0? Si la valeur correspond au r\u00e9sultat d\u2019une \u00e9valuation, peut-on en quelque sorte \u00e9valuer l\u2019\u00e9valuation\u00a0? Un tel redoublement du questionnement, qui est le propre &hellip; <\/p>\n","protected":false},"author":1,"featured_media":3466,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[60,93],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3465"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3465"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}