{"id":3312,"date":"2021-05-25T11:02:55","date_gmt":"2021-05-25T09:02:55","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=3312"},"modified":"2021-05-25T11:02:55","modified_gmt":"2021-05-25T09:02:55","slug":"une-relocalisation-eco-solidaire-et-ecologique-soppose-a-la-mondialisation-liberale-et-au-protectionnisme-nationaliste","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/05\/25\/une-relocalisation-eco-solidaire-et-ecologique-soppose-a-la-mondialisation-liberale-et-au-protectionnisme-nationaliste\/","title":{"rendered":"Relocalisation eco-solidaire et \u00e9cologique, oppos\u00e9e \u00e0 la mondialisation lib\u00e9rale et au protectionnisme nationaliste"},"content":{"rendered":"<p style=\"text-align: justify;\">En 2018, Donald Trump, pr\u00e9sident des Etats-Unis, instaure une s\u00e9rie de mesures protectionnistes contre plusieurs pays, tels que la Chine ou l\u2019Europe. Cette d\u00e9cision redistribue les cartes et les strat\u00e9gies du commerce mondial. Du c\u00f4t\u00e9 de la gauche radicale, \u00e0 l&#8217;instar des partis politiques comme la France insoumise et les \u00e9co-socialistes, le projet politique consiste \u00e0 opter pour une relocalisation \u00e9co-solidaire et \u00e9cologiste, aussi d\u00e9nomm\u00e9e \u00ab protectionnisme solidaire \u00bb. Il en est de m\u00eame avec Arnaud Montebourg,\u00a0 candidat pour les primaires du parti socialiste en vue des pr\u00e9sidentielles de 2012, lorsqu&#8217;il a d\u00e9fend une \u00ab <a href=\"https:\/\/www.cairn.info\/revue-savoir-agir-2012-1-page-89.htm\">d\u00e9mondialisation<\/a>\u00a0\u00bb. Il proposait d\u2019instaurer \u00ab\u00a0une taxe carbone ext\u00e9rieure aux fronti\u00e8res de l\u2019UE, afin que les produits import\u00e9s refl\u00e8tent leur \u00ab\u00a0juste co\u00fbt carbone, sanitaire et social\u00a0\u00bb<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>.<\/p>\n<h2>Les forces id\u00e9ologiques en pr\u00e9sence<\/h2>\n<p style=\"text-align: justify;\">Quels sont les points communs et les diff\u00e9rences entre les diff\u00e9rentes approches de la gauche centriste, radicale ou extr\u00eame ? La caract\u00e9ristique principale de la gauche r\u00e9side dans la volont\u00e9 d\u2019une \u00e9galisation \u00e9conomique, via une redistribution des richesses; \u00e0 l\u2019inverse, la droite lib\u00e9rale\u00a0 privil\u00e9gie\u00a0 les in\u00e9galit\u00e9s au nom de la libert\u00e9 \u00e9conomique. Les\u00a0 orientations politiques qui pr\u00f4nent la relocalisation sociale (de gauche) ou la relocalisation de droite (la droite de l\u2019ordre, de la tradition ou la droite autoritaire) s\u2019inscrivent toutes contre la mondialisation n\u00e9olib\u00e9rale des \u00e9changes et du commerce. En revanche, elles restent largement antagonistes entre elles, lorsqu\u2019elles d\u00e9clinent leurs propositions. les divergences portent aussi bien sur les questions \u00e9cologique, sociale, \u00e9conomique, d\u00e9mocratique que protectionniste&#8230; Par cons\u00e9quent, il serait une erreur d&#8217;envisager une union id\u00e9ologique autour d\u2019une politique de relocalisation indiff\u00e9renci\u00e9e et unifi\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Un d\u00e9veloppement autonome suppose une <a href=\"https:\/\/www.cairn.info\/revue-economique-de-l-ocde-2004-1-page-75.htm\">relocalisation<\/a> globale ou s\u00e9lective (c\u2019est \u00e0 dire partielle), de m\u00eame que le droit \u00e0 un certain protectionnisme. L\u2019autonomie \u00e9conomique s\u2019av\u00e8re d\u2019ailleurs la condition pr\u00e9alable \u00e0 l\u2019ouverture \u00e9conomique, sinon l\u2019\u00e9conomie nationale risque d\u2019\u00eatre domin\u00e9e par les entreprises transnationales \u00e9trang\u00e8res. L\u2019autonomie suppose aussi de d\u00e9velopper l\u2019agriculture vivri\u00e8re en vue d&#8217;atteindre l\u2019autosuffisance. Cette forme d&#8217;agriculture permet aux populations de se nourrir par elle-m\u00eame. A l\u2019inverse, la mondialisation lib\u00e9rale fait la promotion d\u2019une production locale tourn\u00e9e vers l\u2019exportation de produits qui ne rel\u00e8vent pas d\u2019une consommation locale essentielle&#8230; Certaines ONG, comme les membres de MINGA, (une f\u00e9d\u00e9ration d\u2019acteurs du commerce \u00e9quitable) cherchent \u00e0 int\u00e9grer les principes de la relocalisation \u00e9co-solidaire.<\/p>\n<h2>Les oppositions<\/h2>\n<p style=\"text-align: justify;\">Dans le mod\u00e8le de la mondialisation des \u00e9changes, fond\u00e9 sur le capitalisme lib\u00e9ral, et plus largement le productivisme, le transport s\u2019inscrit lui aussi, dans un projet de croissance mondiale infinie. La relocalisation \u00e9conomique s\u2019inscrit dans une lutte contre la d\u00e9localisation et la perte d\u2019autonomie du d\u00e9veloppement \u00e9conomique local. Elle consiste \u00e0 produire localement, afin de d\u00e9velopper l&#8217;autonomie \u00e9conomique, politique, culturelle. Elle vise \u00e9galement \u00e0 diminuer l&#8217;empreinte \u00e9cologique et l&#8217;empreinte carbone. Serge Latouche d\u00e9finit la relocalisation comme le fait de \u00ab produire localement pour l&#8217;essentiel les produits servant \u00e0 la satisfaction des besoins de la population \u00e0 partir d&#8217;entreprises locales financ\u00e9es par l&#8217;\u00e9pargne collect\u00e9e localement \u00bb<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Les principales oppositions entre le lib\u00e9ralisme \u00e9conomique et la relocalisation \u00e9co-solidaire<\/strong><\/p>\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Lib\u00e9ralisme \u00e9conomique<\/td><td>Relocalisation \u00e9co-solidaire (ou d\u00e9veloppement local autonome et solidaire)<\/td><\/tr><tr><td>Th\u00e9orie des avantages comparatifs et sp\u00e9cialisations (Ricardo)<br>Concurrence \/comp\u00e9tition<br>Ouverture des fronti\u00e8res<br>Plus de privatisation et moins de r\u00e9gulation par les pouvoirs publics<br>Libert\u00e9, donc plus de diff\u00e9renciation et d\u2019in\u00e9galit\u00e9s (\u00e9conomique, sociale, gouvernementale, culturelle, \u00e9cologique&#8230;)<\/td><td>Th\u00e9orie de l\u2019in\u00e9galit\u00e9 des termes de l\u2019\u00e9change (Marxiste)<br>Coop\u00e9ration<br>Protectionnisme<br>Plus de services publics et de r\u00e9gulation par les pouvoirs publics<br>Egalit\u00e9, donc moins de libert\u00e9 (\u00e9conomique, sociale, gouvernementale, culturelle, \u00e9cologique&#8230;)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<p>\u00a0<\/p>\n<p style=\"text-align: justify;\">Face \u00e0 ces enjeux, Alain Liepietz s\u2019interroge : \u00ab le d\u00e9veloppement local peut-il devenir une alternative au mod\u00e8le de d\u00e9veloppement lib\u00e9ral dominant au plan mondial ? (&#8230;) Deux strat\u00e9gies existent en effet : la premi\u00e8re est le d\u00e9veloppement du travail de la communaut\u00e9 pour la communaut\u00e9 ; dans la seconde, la communaut\u00e9 construit une \u2019\u2019 base exportatrice \u2019\u2019 vers les march\u00e9s ext\u00e9rieurs. Tout mod\u00e8le de d\u00e9veloppement local est une combinaison des deux, les \u00e9cologistes et les alternatifs en g\u00e9n\u00e9ral, insistant sur le premier terme, plus que sur le second \u00bb<a href=\"#_ftn1\" name=\"_ftnref1\"><em><strong>[3]<\/strong><\/em><\/a>.<\/p>\n<p style=\"text-align: justify;\">Un arr\u00eat int\u00e9gral de l\u2019importation en France repr\u00e9senterait un quart du PIB fran\u00e7ais. Dans le cadre d\u2019une politique de stabilit\u00e9 de la consommation, donc de la production, cela aurait pour cons\u00e9quence de pousser les entreprises fran\u00e7aises \u00e0 compenser, en produisant 25 % en plus. Cependant, la perspective \u00e9cologiste pousserait plut\u00f4t \u00e0 profiter de ce changement \u00e9conomique, pour ne pas compenser int\u00e9gralement la baisse de la production, afin de la limiter en partie, dans la mesure o\u00f9 celle-ci nuit \u00e0 l\u2019empreinte carbone et \u00e9cologique.<\/p>\n<p style=\"text-align: right;\"><a href=\"http:\/\/observatoire-asap.org\/index.php\/2021\/05\/25\/thierry-brugvin\/\">Thierry Brugvin<\/a><\/p>\n\n\n<p><strong>R\u00e9f\u00e9rences<\/strong><\/p>\n\n\n\n<p><a href=\"#_ftnref1\">[1]<\/a> Montebourg A. (2011), <em>Votez pour la d\u00e9mondialisation<\/em>, Flammarion, 92 p.,.<\/p>\n\n\n\n<p><a href=\"#_ftnref2\">[2]<\/a> Latouche S. (2006), Le <em>pari de la d\u00e9croissance<\/em>, Fayard, 302 p.<\/p>\n\n\n\n<p><a href=\"#_ftnref1\">[3]<\/a> Liepietz A. (2002), \u00ab&nbsp;Du d\u00e9veloppement local au d\u00e9veloppement durable&nbsp;: Limites d\u2019une pratique, perspectives de deux id\u00e9ologies&nbsp;\u00bb, <em>Territoires<\/em> n\u00b0431, Octobre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2018, Donald Trump, pr\u00e9sident des Etats-Unis, instaure une s\u00e9rie de mesures protectionnistes contre plusieurs pays, tels que la Chine ou l\u2019Europe. Cette d\u00e9cision redistribue les cartes et les strat\u00e9gies du commerce mondial. Du c\u00f4t\u00e9 de la gauche radicale, \u00e0 l&#8217;instar des partis politiques comme la France insoumise et les \u00e9co-socialistes, le projet politique consiste &hellip; <\/p>\n","protected":false},"author":1,"featured_media":3313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[60],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3312"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3312"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}