{"id":3288,"date":"2021-05-11T12:28:56","date_gmt":"2021-05-11T10:28:56","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=3288"},"modified":"2021-05-11T12:28:56","modified_gmt":"2021-05-11T10:28:56","slug":"entretien-aupres-de-veronique-deborde-directrice-de-la-fondation-partenariale-de-lupec","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/05\/11\/entretien-aupres-de-veronique-deborde-directrice-de-la-fondation-partenariale-de-lupec\/","title":{"rendered":"Entretien aupr\u00e8s de V\u00e9ronique Deborde, directrice de la Fondation partenariale de l&#8217;UPEC"},"content":{"rendered":"<p>Entretien men\u00e9 par <a href=\"http:\/\/observatoire-asap.org\/index.php\/2020\/02\/02\/lolita-rubens\/\">Lolita Rubens<\/a><\/p>\n<p><strong>Pouvez-vous vous pr\u00e9senter ?<\/strong><\/p>\n<p style=\"text-align: justify;\">Je suis V\u00e9ronique Deborde et j\u2019ai rejoint l\u2019Universit\u00e9 Paris Est Cr\u00e9teil (UPEC) en septembre 2020 pour achever la cr\u00e9ation de la <a href=\"https:\/\/www.u-pec.fr\/fr\/universite\/fondation-upec\">Fondation partenariale de l\u2019UPEC<\/a>, projet sur lequel l\u2019\u00e9quipe pr\u00e9sidentielle \u00e9tait d\u00e9j\u00e0 fortement engag\u00e9e depuis plus d\u2019une ann\u00e9e. Une fois la Fondation officiellement cr\u00e9\u00e9e en janvier 2021, j\u2019ai \u00e9t\u00e9 nomm\u00e9e Directrice avec pour mission d\u2019en d\u00e9velopper les ressources, d\u2019identifier et suivre la mise en \u0153uvre des projets qui seront financ\u00e9s et d\u2019assurer les relations avec les partenaires, m\u00e9c\u00e8nes et donateurs qui soutiendront ses activit\u00e9s.<br \/>\nJe connais bien le domaine des fondations adoss\u00e9es \u00e0 des \u00e9tablissements d\u2019enseignement sup\u00e9rieur puisque j\u2019ai cr\u00e9\u00e9 puis dirig\u00e9 la <a href=\"https:\/\/www.fondation-mines-telecom.org\/\">Fondation Mines-Telecom<\/a>, Fondation Reconnue d\u2019Utilit\u00e9 Publique qui \u0153uvre en faveur du d\u00e9veloppement de l\u2019Institut Mines-Telecom et de ses 8 grandes \u00e9coles d\u2019ing\u00e9nieurs et de management. En une quinzaine d\u2019ann\u00e9es, la Fondation Mines-Telecom a lev\u00e9 au b\u00e9n\u00e9fice des \u00e9coles de l\u2019IMT, plus de 65 M\u20ac \u00e0 travers de nombreux partenariats de m\u00e9c\u00e9nat avec des entreprises et par des dons de particuliers pour soutenir des projets d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral dans le domaine de la formation, de la recherche, de l\u2019innovation, de la solidarit\u00e9 et de l\u2019ouverture sociale ainsi qu\u2019une vingtaine de chaires au b\u00e9n\u00e9fice des \u00e9coles de l\u2019IMT.<\/p>\n<p style=\"text-align: justify;\">Je mets aujourd\u2019hui mon exp\u00e9rience acquise dans le montage et l\u2019ing\u00e9nierie de projets partenariaux de m\u00e9c\u00e9nat au b\u00e9n\u00e9fice de l\u2019UPEC pour faire de sa fondation un outil de d\u00e9veloppement sur le long terme de ses coop\u00e9rations avec les acteurs socio-\u00e9conomiques de son \u00e9cosyst\u00e8me en faveur de l\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral.<\/p>\n<p><strong>Pourquoi avoir cr\u00e9\u00e9 une Fondation \u00e0 l&#8217;UPEC ? En quoi cela participe \u00e0 am\u00e9liorer l&#8217;impact de l&#8217;UPEC en termes d&#8217;action soci\u00e9tale selon vous ?<\/strong><\/p>\n<p style=\"text-align: justify;\">La fondation partenariale de l\u2019UPEC s\u2019inscrit comme un des leviers majeurs du <a href=\"https:\/\/www.u-pec.fr\/fr\/universite\/strategie-et-grands-projets\">projet strat\u00e9gique 2020-2024<\/a> de l\u2019\u00e9tablissement, nourrissant sa vision d\u2019universit\u00e9 engag\u00e9e au c\u0153ur des transformations soci\u00e9tales et environnementales, au service de toutes les excellences.<\/p>\n<p style=\"text-align: justify;\">Elle va aussi permettre d\u2019apporter \u00e0 l\u2019Universit\u00e9 des moyens nouveaux pour soutenir ses ambitions, et porter des projets d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral p\u00e9dagogiques et scientifiques ainsi que des actions de solidarit\u00e9 avec des approches innovantes et transdisciplinaires. Elle inscrit son action autour des enjeux li\u00e9s aux vuln\u00e9rabilit\u00e9s et \u00e0 leurs impacts sur l\u2019environnement, la sant\u00e9 et la soci\u00e9t\u00e9 pour accompagner l\u2019UPEC sur ces d\u00e9fis majeurs.<\/p>\n<p style=\"text-align: justify;\">Con\u00e7ue comme un espace d\u2019\u00e9changes et d\u2019exp\u00e9rimentation soci\u00e9tale et un catalyseur de partenariats, la fondation offre aussi \u00e0 l\u2019UPEC une opportunit\u00e9 unique de d\u00e9velopper, dans un cadre ouvert, ses relations avec son environnement socio-\u00e9conomique, \u00e0 renforcer ses liens avec les acteurs de son territoire, et bien s\u00fbr \u00e0 accroitre ses ressources propres.<\/p>\n<p style=\"text-align: justify;\">La Fondation a permis d\u2019associer \u00e0 sa cr\u00e9ation, aux c\u00f4t\u00e9s de l\u2019UPEC, quatre partenaires historiques de l\u2019Universit\u00e9 \u2013 BNP Paribas, Thal\u00e8s, l\u2019Agefiph et le Conseil D\u00e9partemental 77-\u00a0 partageant les valeurs de la Fondation et associ\u00e9s \u00e0 son premier plan d\u2019action pluriannuel.<\/p>\n<p><strong>Quels sont les projets qui int\u00e9ressent la Fondation ? Comment les soumettre ?<\/strong><\/p>\n<p style=\"text-align: justify;\">La Fondation a dans une premi\u00e8re phase articul\u00e9 ses actions autour de trois th\u00e9matiques phares et f\u00e9d\u00e9ratrices\u00a0: le Handicap et l\u2019inclusion\u00a0; l\u2019Environnement et les trajectoires de sant\u00e9, et l\u2019Entreprise de demain, pour accompagner la transformation des organisations, en lien avec les nouveaux besoins en comp\u00e9tences, les nouveaux m\u00e9tiers et les enjeux li\u00e9s \u00e0 la diversit\u00e9.<\/p>\n<p style=\"text-align: justify;\">Bien entendu, d\u2019autres th\u00e9matiques seront ensuite adress\u00e9es en fonction des besoins identifi\u00e9s par l\u2019Universit\u00e9 et ses \u00e9quipes acad\u00e9miques puisque la Fondation se positionne comme un outil au service de l\u2019ensemble de communaut\u00e9 UPEC et de ses composantes.<br \/>\nDans cette perspective, l\u2019Universit\u00e9 a d\u00e9cid\u00e9 de mettre en place un Comit\u00e9 Projets dont les membres repr\u00e9senteront l\u2019ensemble des axes disciplinaires de l\u2019UPEC afin d\u2019identifier les nouveaux projets \u00e0 lancer, v\u00e9rifier qu\u2019ils puissent s\u2019inscrire dans le cadre d\u2019un partenariat de m\u00e9c\u00e9nat et \u00e0 \u00e9valuer ceux d\u00e9j\u00e0 financ\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Tout nouveau projet de m\u00e9c\u00e9nat pourra dont \u00eatre soumis dans le cadre de cette instance. Les responsables des projets s\u00e9lectionn\u00e9s seront ainsi m\u00e9thodologiquement accompagn\u00e9s par la Fondation dans leurs d\u00e9marches de lev\u00e9es de fonds aupr\u00e8s de potentiels financeurs, puisque, \u00e0 ce stade, la Fondation ne dispose pas de fonds libres d\u00e9j\u00e0 disponibles mais organise la prospection de potentiels m\u00e9c\u00e8nes en coop\u00e9ration avec les porteurs de projets.<\/p>\n<p style=\"text-align: justify;\"><strong>Quels sont les projets d\u00e9j\u00e0 en cours ?<\/strong><br \/>\n<strong><br \/>\n<\/strong>Une dizaine de projets s\u2019inscrivant dans les trois premi\u00e8res th\u00e9matiques de la fondation ont d\u00e9j\u00e0 \u00e9t\u00e9 d\u00e9finis pour d\u00e9marrer prochainement une d\u00e9marche de lev\u00e9es de fonds aupr\u00e8s de m\u00e9c\u00e8nes entreprises et particuliers.<\/p>\n<p style=\"text-align: justify;\">Sur le volet Handicap, on peut notamment citer la Chaire Handicap, Emploi et Sant\u00e9 au Travail, qui a d\u2019ores et d\u00e9j\u00e0 pu concr\u00e9tiser plusieurs partenariats ou encore le d\u00e9veloppement d\u2019un outil simple et r\u00e9volutionnaire pour diagnostiquer de mani\u00e8re tr\u00e8s pr\u00e9coce la maladie de Parkinson.<\/p>\n<p style=\"text-align: justify;\">Sur le sujet de l\u2019environnement, l\u2019<a href=\"https:\/\/www.u-pec.fr\/fr\/universite\/strategie-et-grands-projets\/eur-live\">\u00c9cole Universitaire de Recherche LIVE<\/a>, sur les trajectoires et les vuln\u00e9rabilit\u00e9s en sant\u00e9 souhaite consolider son financement avec le soutien de la Fondation \u00e0 travers des partenariats de m\u00e9c\u00e9nat.<\/p>\n<p style=\"text-align: justify;\">Enfin sur la th\u00e9matique de la transformation sociale des entreprises et les nouvelles formes d\u2019apprentissage, l\u2019UPEC souhaite mettre en place, avec le soutien de m\u00e9c\u00e8nes de la Fondation, la cr\u00e9ation et l\u2019\u00e9quipement d\u2019un Fab Lab innovant, con\u00e7u sur un mode durable install\u00e9 au sein de \u00a0la <a href=\"https:\/\/www.u-pec.fr\/fr\/entreprises-et-partenaires\/la-maison-de-l-innovation-et-de-l-entrepreneuriat-etudiant-miee\">Maison de l\u2019Innovation et de l\u2019Entrepreneuriat Etudiant<\/a>.<\/p>\n<p style=\"text-align: justify;\">Par ailleurs et \u00e0 tr\u00e8s court terme, en r\u00e9ponse aux situations d\u2019urgence auxquelles sont confront\u00e9s les \u00e9tudiants de l\u2019Universit\u00e9 face \u00e0 la crise sanitaire, la Fondation a cr\u00e9\u00e9 un <a href=\"https:\/\/www.u-pec.fr\/fr\/universite\/actualites\/fondation-upec-fonds-daides-durgence-crise-sanitaire\">fonds d\u2019urgence<\/a> destin\u00e9 \u00e0 recueillir des dons pour leur venir en aide, en particulier sur le volet du logement et de l\u2019isolement social, en compl\u00e9ment des actions d\u00e9j\u00e0 d\u00e9ploy\u00e9es par l\u2019UPEC.<\/p>\n<p style=\"text-align: justify;\">\u00a0<strong>Quels sont les objectifs \u00e0 court et plus long terme ?<\/strong><\/p>\n<p style=\"text-align: justify;\">A court terme, nous souhaitons pouvoir \u00e9largir encore le cercle des co-fondateurs de la Fondation en int\u00e9grant d\u2019autres entreprises et collectivit\u00e9s territoriales d\u00e9sireuses de s\u2019engager, sur le long terme, aux c\u00f4t\u00e9s de l\u2019Universit\u00e9 pour l\u2019accompagner dans ses ambitions soci\u00e9tales sur les grandes th\u00e9matiques phares port\u00e9es par l\u2019Universit\u00e9. Nous allons donc aller pr\u00e9senter, la Fondation, sa vision et ses projets aux acteurs socio-\u00e9conomiques d\u00e9j\u00e0 proches de l\u2019UPEC pour les convaincre de s\u2019engager plus avant dans un partenariat porteur de valeur avec la Fondation.<\/p>\n<p style=\"text-align: justify;\">En parall\u00e8le, les projets d\u00e9j\u00e0 \u00e9labor\u00e9s vont \u00eatre pr\u00e9sent\u00e9s aux m\u00e9c\u00e8nes potentiels pour rechercher les financements dont ils ont besoin pour leur r\u00e9alisation.<br \/>\nDe nouveaux projets vont aussi, nous l\u2019esp\u00e9rons, \u00e9merger gr\u00e2ce \u00e0 la mise en place du Comit\u00e9 Projets et notamment des Chaires d\u2019enseignement-Recherche qui constituent des objets de partenariats tr\u00e8s appr\u00e9ci\u00e9es des entreprises dans le cadre du m\u00e9c\u00e9nat pour co-construire et soutenir dans un cadre ouvert des programmes p\u00e9dagogiques et scientifiques sur des th\u00e9matiques en lien avec les probl\u00e9matiques du monde socio-\u00e9conomique.<\/p>\n<p style=\"text-align: justify;\">Des actions de communication et de visibilit\u00e9 sur les projets de la Fondation vont aussi \u00eatre d\u00e9ploy\u00e9es vis-\u00e0-vis des particuliers, <em>alumni <\/em>et amis de l\u2019UPEC, pour mobiliser les g\u00e9n\u00e9rosit\u00e9s sur les actions de solidarit\u00e9 vis-\u00e0-vis des \u00e9tudiants et en illustrer l\u2019impact, la Fondation pouvant \u00eatre un outil puissant de mobilisation et de d\u00e9veloppement d\u2019un <em>affectio societatis<\/em> de la communaut\u00e9 UPEC sur ces sujets.<\/p>\n<p style=\"text-align: justify;\">A plus long terme, nous esp\u00e9rons bien s\u00fbr que la Fondation puisse devenir pour l\u2019Universit\u00e9 et l\u2019ensemble de ses composantes, un espace incontournable et un lieu d\u2019\u00e9changes permanent pour initier et d\u00e9ployer des coop\u00e9rations sur le long terme et contribuer \u00e0 structurer ses relations partenariales tout en d\u00e9veloppant ses ressources.<\/p>\n<p style=\"text-align: justify;\"><strong>Comment peut-on soutenir \u00e0 la Fondation ?<\/strong><\/p>\n<p style=\"text-align: justify;\">C\u2019est tr\u00e8s simple. Que l\u2019on soit particulier ou entreprise, il est possible de faire un don \u00e0 la Fondation d\u2019un simple clic <a href=\"https:\/\/soutenir-fondation-upec.iraiser.eu\/b\/mon-don?cid=1&amp;_cv=1\">sur un formulaire d\u00e9di\u00e9<\/a>. Il est possible de choisir d\u2019affecter ce soutien \u00e0 la Fondation ou bien de mani\u00e8re plus cibl\u00e9e et pour r\u00e9pondre \u00e0 l\u2019urgence de la crise sanitaire, de donner pour le fonds d\u2019urgence.<\/p>\n<p style=\"text-align: justify;\">Bien entendu, tout don donne droit \u00e0 un re\u00e7u fiscal permettant une d\u00e9duction pour les particuliers de 66% de l\u2019Imp\u00f4t sur le revenu (un don de 100 \u20ac revient \u00e0 44 \u20ac !) et pour les entreprises une d\u00e9duction de 60% de l\u2019Imp\u00f4t sur les Soci\u00e9t\u00e9s (un don de 10.000 \u20ac revient ainsi \u00e0 4000 \u20ac !).<\/p>\n<p style=\"text-align: justify;\">Il est aussi possible de choisir de cibler son soutien sur un des projets de la Fondation ou bien de d\u00e9cider de soutenir une des grandes th\u00e9matiques phares Handicap\u00a0; Sant\u00e9\/Environnement\/Soci\u00e9t\u00e9 ou Entreprise de demain\u2026<\/p>\n<p style=\"text-align: justify;\">Les engagements des entreprises sont formalis\u00e9s dans une convention de m\u00e9c\u00e9nat pr\u00e9cisant l\u2019utilisation du don et le programme de reconnaissance accord\u00e9 en contrepartie.<\/p>\n<p style=\"text-align: justify;\">Je pr\u00e9cise que chaque don est affect\u00e9 selon la volont\u00e9 du donateur au projet qu\u2019il a s\u00e9lectionn\u00e9 et que les comptes dela Fondation sont contr\u00f4l\u00e9s chaque ann\u00e9e par un commissaire aux comptes, garantissant s\u00e9rieux et transparence dans la gestion.<\/p>\n<p style=\"text-align: justify;\">Pour tout renseignement : V\u00e9ronique Deborde, Directrice de la Fondation<br \/>\n<a href=\"mailto:veronique.deborde@u-pec.fr\">veronique.deborde@u-pec.fr<\/a><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Entretien men\u00e9 par Lolita Rubens Pouvez-vous vous pr\u00e9senter ? Je suis V\u00e9ronique Deborde et j\u2019ai rejoint l\u2019Universit\u00e9 Paris Est Cr\u00e9teil (UPEC) en septembre 2020 pour achever la cr\u00e9ation de la Fondation partenariale de l\u2019UPEC, projet sur lequel l\u2019\u00e9quipe pr\u00e9sidentielle \u00e9tait d\u00e9j\u00e0 fortement engag\u00e9e depuis plus d\u2019une ann\u00e9e. Une fois la Fondation officiellement cr\u00e9\u00e9e en janvier &hellip; <\/p>\n","protected":false},"author":1,"featured_media":3294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[60],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3288"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3288"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}