{"id":3146,"date":"2021-04-27T09:38:34","date_gmt":"2021-04-27T07:38:34","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=3146"},"modified":"2021-04-27T09:38:34","modified_gmt":"2021-04-27T07:38:34","slug":"nicolas-anne","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/04\/27\/nicolas-anne\/","title":{"rendered":"Nicolas Anne"},"content":{"rendered":"<p style=\"text-align: justify;\">Titulaire d\u2019un master Prospective Innovation, strat\u00e9gie et organisation, <strong>Nicolas Anne<\/strong> a men\u00e9 diff\u00e9rentes missions de marketing strat\u00e9gique aupr\u00e8s de grands groupes et de start-ups. Il a \u00e9galement men\u00e9 des missions de conseil en entreprise sur les strat\u00e9gies d\u2019implantation territoriale et de collaborations franco-chinoises. Parall\u00e8lement \u00e0 ses activit\u00e9s de conseil, <strong>il s\u2019investit dans \u00a0l\u2019enseignement de l\u2019\u00e9conomie dans les quartiers prioritaires et aupr\u00e8s des populations fragiles<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>En 2016, il rejoint<\/strong> <strong>l\u2019enseignement sup\u00e9rieur<\/strong> puis int\u00e8gre PPA Business School. En tant qu\u2019enseignant-chercheur permanent, il poursuit actuellement des \u00e9tudes doctorales sur les strat\u00e9gies d\u2019innovation, et en particulier sur les \u00e9volutions des <strong>\u00e9cosyst\u00e8mes d\u2019affaires priv\u00e9s-publics de l\u2019industrie culturelle<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Titulaire d\u2019un master Prospective Innovation, strat\u00e9gie et organisation, Nicolas Anne a men\u00e9 diff\u00e9rentes missions de marketing strat\u00e9gique aupr\u00e8s de grands groupes et de start-ups. Il a \u00e9galement men\u00e9 des missions de conseil en entreprise sur les strat\u00e9gies d\u2019implantation territoriale et de collaborations franco-chinoises. Parall\u00e8lement \u00e0 ses activit\u00e9s de conseil, il s\u2019investit dans \u00a0l\u2019enseignement de l\u2019\u00e9conomie &hellip; <\/p>\n","protected":false},"author":1,"featured_media":3147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3146"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3146"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}