{"id":3034,"date":"2021-04-13T22:58:02","date_gmt":"2021-04-13T20:58:02","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=3034"},"modified":"2021-04-13T22:58:02","modified_gmt":"2021-04-13T20:58:02","slug":"onlylyon-une-organisation-unique-de-promotion-territoriale","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/04\/13\/onlylyon-une-organisation-unique-de-promotion-territoriale\/","title":{"rendered":"ONLYLYON, une organisation unique de promotion territoriale"},"content":{"rendered":"<p>ONLYLYON est la marque officielle de la ville de Lyon et une organisation en r\u00e9seau dont l\u2019ambition est de d\u00e9velopper l\u2019attractivit\u00e9 territoriale de Lyon. L&#8217;organisation associe des acteurs publics et priv\u00e9s, et s&#8217;appuie sur 27.000 ambassadeurs qui font la promotion de la ville. Comment fonctionne cette organisation unique qui fait rayonner la ville de Lyon en France et \u00e0 l\u2019international ? Pour r\u00e9pondre \u00e0 cette interrogation, nous allons pr\u00e9senter les caract\u00e9ristiques de l\u2019organisation et le r\u00f4le de ses ambassadeurs avant de mettre en relief les r\u00e9sultats de la collaboration territoriale engag\u00e9e.<\/p>\n\n\n<h2 class=\"wp-block-heading\">Une organisation d\u2019acteurs publics et priv\u00e9s pour d\u00e9velopper l\u2019attractivit\u00e9 de la ville<\/h2>\n\n\n\n<p>Cr\u00e9\u00e9 en 2007 \u00e0 l&#8217;initiative du maire de la ville, ONLYLYON f\u00e9d\u00e8re 13 membres fondateurs qui sont des acteurs institutionnels et \u00e9conomiques du territoire lyonnais et dix entreprises partenaires qui sont fortement implant\u00e9es dans la r\u00e9gion (voir Tableau). La <a href=\"https:\/\/www.lesechos.fr\/idees-debats\/cercle\/la-cohesion-territoriale-notre-responsabilite-dentreprise-1016671\">cr\u00e9ation de la marque ONLYLYON<\/a> leur permet de partager leurs moyens pour d\u00e9velopper des actions communes ayant un impact plus fort sur leur territoire. Les acteurs associ\u00e9s coop\u00e8rent dans l\u2019objectif de contribuer au d\u00e9veloppement et au rayonnement de la ville.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"http:\/\/observatoire-asap.org\/wp-content\/uploads\/2021\/04\/tableau-1-1024x612.png\" alt=\"\" class=\"wp-image-3053\"\/><\/figure>\n\n\n\n<p>Compos\u00e9e de dix personnes, l\u2019\u00e9quipe op\u00e9rationnelle d\u2019ONLYLYON est charg\u00e9e de g\u00e9rer et de communiquer sur les activit\u00e9s et les projets de l\u2019organisation. Elle soutient les initiatives prises par les membres fondateurs et les entreprises partenaires, et anime le r\u00e9seau des ambassadeurs. Elle organise des \u00e9v\u00e9nements mensuels, appel\u00e9s \u00ab One and Only \u00bb, pour r\u00e9unir les ambassadeurs autour d\u2019une th\u00e9matique d\u2019actualit\u00e9 li\u00e9e \u00e0 la ville.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Un r\u00e9seau de 27.000 ambassadeurs pour faire rayonner la ville<\/h2>\n\n\n\n<p>ONLYLYON s\u2019appuie sur un r\u00e9seau de 27.000 ambassadeurs, c\u2019est-\u00e0-dire des personnes qui font la promotion de la ville de Lyon en France et \u00e0 l\u2019international. Il s\u2019agit de Lyonnais de naissance ou d&#8217;adoption qui contribuent \u00e0 promouvoir Lyon par leurs activit\u00e9s et leur attachement \u00e0 la ville. Ils peuvent choisir les actions qu\u2019ils souhaitent d\u00e9velopper, par exemple, promouvoir les activit\u00e9s propos\u00e9es par la ville, inviter des personnalit\u00e9s dans la ville et mettre place des relations entre les acteurs du territoire lyonnais et d\u2019autres r\u00e9gions ou pays. En contrepartie, les ambassadeurs actifs re\u00e7oivent des r\u00e9compenses telles que la \u00ab&nbsp;Lyon City Card&nbsp;\u00bb (qui offre de nombreux avantages pour visiter la ville), le \u00ab&nbsp;Lion Rouge&nbsp;\u00bb et des billets gratuits pour des manifestations culturelles et sportives, qui sont offerts par ONLYLYON, les membres fondateurs et les entreprises partenaires.<\/p>\n\n\n\n<p>5.000 ambassadeurs vivent \u00e0 l&#8217;\u00e9tranger et <a href=\"https:\/\/business.lesechos.fr\/entrepreneurs\/aides-reseaux\/0602192304617-lyon-joue-en-ligue-des-champions-en-foot-comme-en-affaires-333051.php\">font rayonner la ville de Lyon<\/a> rayonner la ville de Lyon dans le monde entier. L\u2019organisation a nomm\u00e9 des correspondants \u00e9trangers pour animer les communaut\u00e9s lyonnaises dans des m\u00e9tropoles comme Sao Paulo, Sydney, Moscou, Boston, Montr\u00e9al, Bruxelles, Londres, P\u00e9kin, New York et Tokyo. Leur mission consiste \u00e9galement \u00e0 identifier des opportunit\u00e9s de collaborations \u00e9conomiques, culturelles ou universitaires pour la r\u00e9gion lyonnaise.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Lyon est devenue l\u2019une des villes les plus attractives en Europe<\/h2>\n\n\n\n<p>La cr\u00e9ation d\u2019ONLYLYON a permis de d\u00e9velopper la collaboration entre les acteurs publics et priv\u00e9s dans la promotion de la ville et de mettre en place un vaste r\u00e9seau d\u2019ambassadeurs qui font rayonner Lyon en France et \u00e0 l\u2019\u00e9tranger. La ville figure r\u00e9guli\u00e8rement dans les <a href=\"https:\/\/www.lyoncapitale.fr\/actualite\/lyon-designe-capitale-du-tourisme-intelligent\/\">classements des villes les plus attractives<\/a> en Europe. En 2019, elle remporte la premi\u00e8re place \u00e0 l\u2019occasion du concours \u00ab Capitales europ\u00e9ennes du tourisme intelligent \u00bb, organis\u00e9 par l\u2019Union Europ\u00e9enne.<\/p>\n\n\n\n<p>En 2020, les lecteurs du c\u00e9l\u00e8bre magazine am\u00e9ricain \u00ab Cond\u00e9 Nast Traveller \u00bb classent la capitale des Gaules dans le&nbsp;<a href=\"https:\/\/www.bfmtv.com\/lyon\/lyon-classee-parmi-les-10-meilleures-villes-du-monde-selon-un-magazine-americain_AN-202010120378.html\">Top 10 des meilleures villes du monde<\/a> Top 10 des meilleures villes du monde.<\/p>\n\n\n\n<p>Ces r\u00e9compenses t\u00e9moignent du rayonnement de la ville qui ne cesse de se d\u00e9velopper gr\u00e2ce aux nombreuses actions de promotion territoriale qui sont mises en place par les acteurs publics et priv\u00e9s associ\u00e9s au sein d\u2019ONLYLYON, \u00e0 l\u2019aide d\u2019un vaste r\u00e9seau d\u2019ambassadeurs qui font \u00ab&nbsp;briller&nbsp;\u00bb la ville en France et au-del\u00e0 des fronti\u00e8res.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><span class=\"current\"><a href=\"https:\/\/observatoire-asap.org\/?p=3039\">Stefano Valdemarin<\/a><\/span> et <a href=\"http:\/\/observatoire-asap.org\/index.php\/2020\/11\/21\/ulrike-mayrhofer\/\">Ulrike Mayrhofer<\/a><\/p>\n\n\n\n<p><strong>R\u00e9f\u00e9rences<br><\/strong>Bartoli, A. et Blatrix, C. (2015), <em>Management dans les organisations publiques<\/em>, 4\u00e8me \u00e9d., Dunod.<br>Mayrhofer, U. (2017), <em>Management strat\u00e9gique<\/em>, 4\u00e8me \u00e9d., Editions Br\u00e9al, Coll. Lexifac.<br>Valdemarin, S. (2019), <em>Network development in international organizations : the case of ONLYLYON<\/em>, Th\u00e8se de doctorat en sciences de gestion, Universit\u00e9 de Lyon.<br>Whittington, R., R\u00e9gner, P., Angwin, D., Johnson, G., Scholes, K. et Fr\u00e9ry, F. (2020), <em>Strat\u00e9gique<\/em>, 12\u00e8me \u00e9d., Pearson.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ONLYLYON est la marque officielle de la ville de Lyon et une organisation en r\u00e9seau dont l\u2019ambition est de d\u00e9velopper l\u2019attractivit\u00e9 territoriale de Lyon. L&#8217;organisation associe des acteurs publics et priv\u00e9s, et s&#8217;appuie sur 27.000 ambassadeurs qui font la promotion de la ville. Comment fonctionne cette organisation unique qui fait rayonner la ville de Lyon &hellip; <\/p>\n","protected":false},"author":1,"featured_media":3035,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[73,85],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3034"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=3034"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/3034\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=3034"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=3034"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=3034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}