{"id":2810,"date":"2021-03-23T16:58:25","date_gmt":"2021-03-23T15:58:25","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=2810"},"modified":"2021-03-23T16:58:25","modified_gmt":"2021-03-23T15:58:25","slug":"hybridation-manageriale-et-sante","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/03\/23\/hybridation-manageriale-et-sante\/","title":{"rendered":"Hybridation manag\u00e9riale et sant\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\">Les organisations hybrides, tels que les h\u00f4pitaux sont en tension entre logique manag\u00e9riale et m\u00e9dicale. Au cours des derni\u00e8res d\u00e9cennies, le secteur hospitalier a subi des <a href=\"https:\/\/books.google.fr\/books?hl=fr&amp;lr=&amp;id=XFphDAAAQBAJ&amp;oi=fnd&amp;pg=PT4&amp;dq=le+secteur+hospitalier++r%C3%A9formes+de+gestion.&amp;ots=tAJ05DHIiy&amp;sig=FZSRy8dn-oWlwhfQgZuX2DKTCF4\">r\u00e9formes importantes de gestion.<\/a> Les h\u00f4pitaux, en tant que bureaucraties professionnelles, introduisent, sous une pression coercitive, des contr\u00f4les administratifs au niveau du c\u0153ur op\u00e9rationnel (Kurunm\u00e4ki et al., 2003). La mise en \u0153uvre des techniques de <a href=\"https:\/\/econpapers.repec.org\/paper\/haljournl\/hal-01653745.htm\">lean Management<\/a>, pressions financi\u00e8res, gestion efficiente des ressources allou\u00e9es et logiques de r\u00e9duction de co\u00fbts cr\u00e9e un climat du chiffre et sugg\u00e8rent que l\u2019h\u00f4pital entre dans une phase de r\u00e9duction de gaspillage appel\u00e9 <a href=\"https:\/\/www.cairn.info\/revue-gestion-2000-2012-4-page-89.htm?contenu=article\"><em>slack <\/em>organisationnel<\/a> (Ruiz Moreno et al., 2008).<\/p>\n<p style=\"text-align: justify;\">Les professionnels de sant\u00e9 se retrouvent pris dans de nouveaux dispositifs d\u2019<em>accountability<\/em> (de rendu de compte sur leur activit\u00e9 m\u00e9dicale) et sont sensibilis\u00e9s aux contraintes financi\u00e8res (Grenier et Bernardini-Perinciolo, 2016). L&#8217;introduction de nouvelles logiques issues du secteur priv\u00e9 alt\u00e8re ainsi le statut particulier des m\u00e9decins : on parle alors de \u00ab m\u00e9decins-gestionnaires \u00bb (Burellier et Valette, 2011). Des \u00e9tudes soulignent que les m\u00e9decins s\u2019approprient et s\u2019hybrident \u00e0 des comp\u00e9tences gestionnaires pour r\u00e9pondre aux pressions organisationnelles. Cependant, peu d\u2019\u00e9tudes se focalisent sur les conditions dans lesquelles les m\u00e9decins adoptent des comp\u00e9tences hybrides et se sensibilisent \u00e0 l\u2019<a href=\"https:\/\/www.cairn.info\/revue-gerer-et-comprendre1-2008-1-page-4.htm\"><em>accountability<\/em><\/a><em> (<\/em>Kurunm\u00e4ki, 2004).<\/p>\n<p style=\"text-align: justify;\">Dans notre recherche, il nous est apparu int\u00e9ressant de nous arr\u00eater sur les conditions n\u00e9cessaires \u00e0 la sensibilisation des m\u00e9decins \u00e0 la logique d\u2019<em>accountability <\/em>dans leur activit\u00e9 quotidienne et sur les effets de ce \u00ab&nbsp;climat d\u2019<em>accountability <\/em>\u00bb au sein de la sph\u00e8re m\u00e9dicale.<\/p>\n<p style=\"text-align: justify;\">A partir de ces questionnements, deux apports majeurs ont \u00e9merg\u00e9.<\/p>\n<p style=\"text-align: justify;\">Premi\u00e8rement, nous avons mis en \u00e9vidence le r\u00f4le essentiel des Techniciens d\u2019Information M\u00e9dicale (TIM, acteurs administratifs) dans l<strong>\u2019<\/strong><a href=\"https:\/\/halshs.archives-ouvertes.fr\/halshs-00534720\/\">hybridation<\/a> des m\u00e9decins aux comp\u00e9tences gestionnaires.<\/p>\n<p style=\"text-align: justify;\">Le montant du budget allou\u00e9 aux \u00e9tablissements en fonction de leur activit\u00e9 est d\u2019une importance cruciale puisqu\u2019il repr\u00e9sente la majeure partie des financements que les h\u00f4pitaux per\u00e7oivent. Le codage de l\u2019activit\u00e9 m\u00e9dicale, qui est de la responsabilit\u00e9 des praticiens, est ainsi strat\u00e9gique d\u2019un point de vue \u00e9conomique. Pour cela, un codage partag\u00e9 voit le jour et conduit des Techniciens en charge de l\u2019information m\u00e9dicale \u00e0 sortir du cadre strict de celle-ci pour sensibiliser les m\u00e9decins au <em>reporting <\/em>de leur activit\u00e9 m\u00e9dicale. En effet, la strat\u00e9gie du D\u00e9partement de l\u2019Information M\u00e9dicale (DIM), de mettre en place un codage partag\u00e9 entre TIM et m\u00e9decins, contribue \u00e0 am\u00e9liorer l\u2019exhaustivit\u00e9 du codage. Par leur interaction fr\u00e9quente avec les m\u00e9decins, les TIM, acteurs administratifs sp\u00e9cifiques, leur permettent d\u2019int\u00e9grer l\u2019importance du <em>reporting <\/em>de leur activit\u00e9, et ainsi de \u00ab rendre des comptes \u00bb.<\/p>\n<p style=\"text-align: justify;\">Cette interaction entre administratifs et m\u00e9decins favorise \u00e9galement une prise de conscience des m\u00e9decins sur l\u2019optimisation d\u2019une prise en charge afin de r\u00e9duire la dur\u00e9e de s\u00e9jour. D\u2019un point de vue op\u00e9rationnel, les m\u00e9decins sont guid\u00e9s par de nombreuses recommandations, comme l\u2019optimisation des prises en charge des patients, et s\u2019alignent en partie sur les recommandations des TIM pour optimiser le financement per\u00e7u de leur activit\u00e9 m\u00e9dicale. Cette derni\u00e8re est ainsi encadr\u00e9e par les indicateurs. &nbsp;L\u2019hybridation des m\u00e9decins aux comp\u00e9tences gestionnaires est r\u00e9alis\u00e9e afin de les sensibiliser au respect des \u00ab normes \u00bb de dur\u00e9e de s\u00e9jour dans le but de r\u00e9duire les co\u00fbts d\u2019hospitalisation. Les objectifs gestionnaires priorisent l\u2019optimisation du financement per\u00e7u et la limitation des co\u00fbts, afin d\u2019afficher des ratios en conformit\u00e9 avec les ratios d\u2019autres \u00e9tablissements. Le DIM ainsi que les TIM endossent un r\u00f4le de \u00ab surveillant \u00bb voire de \u00ab contr\u00f4leur interne \u00bb informel. En effet, les TIM repr\u00e9sentent des vecteurs permettant de contr\u00f4ler l\u2019activit\u00e9 m\u00e9dicale, ainsi que le codage r\u00e9alis\u00e9 par les m\u00e9decins (pouvant adopter des comportements de manipulation de donn\u00e9es). Nous avons constat\u00e9 qu\u2019en soumettant des recommandations concernant des solutions pour r\u00e9duire la dur\u00e9e de prise en charge de leurs patients, les m\u00e9decins s\u2019y conforment dans un premier temps. Cependant la consolidation de nouvelles prises en charge des patients ne perdure pas dans le temps. Nous avons montr\u00e9 \u00e9galement que par leur interaction fr\u00e9quente avec les m\u00e9decins, les TIM tendent \u00e0 renforcer leurs connaissances m\u00e9dicales.<\/p>\n<p style=\"text-align: justify;\">Deuxi\u00e8mement, nous avons soulign\u00e9 qu\u2019apr\u00e8s le support essentiel des TIM pour \u00e9clairer et impliquer les professionnels de sant\u00e9 sur le codage de leur activit\u00e9, d\u2019autres acteurs administratifs s\u2019infiltrent dans les services de soins dans une recherche de r\u00e9duction des surplus. Le changement de logique est manifest\u00e9 et port\u00e9 par la cr\u00e9ation de nouvelles cellules telles que la DOP (Direction des Op\u00e9rations et de la Performance), cr\u00e9\u00e9e pour \u00ab am\u00e9liorer la qualit\u00e9 et la performance \u00bb. Ces gestionnaires importent un vocabulaire du secteur priv\u00e9 et communiquent dans leurs discours l\u2019importance de la r\u00e9duction des surplus, mais \u00e9galement leurs convictions que le CHU peut \u00ab \u00eatre rentable \u00bb. L\u2019importation de ratios, comme ceux introduits par les agents administratifs (les TIM), provient de la comparaison des DMS (Dur\u00e9e Moyenne de S\u00e9jour) des diff\u00e9rentes organisations hospitali\u00e8res. Ceci favorise l\u2019\u00e9mergence d\u2019un syst\u00e8me de mesure de la \u00ab performance \u00bb des CHU. Nous qualifions ce syst\u00e8me de disciplinaire puisqu\u2019il amplifie la cat\u00e9gorisation entre CHU : dans notre \u00e9tude de cas, l\u2019organisation et ainsi son activit\u00e9, est qualifi\u00e9e de \u00ab sur ou sous performante \u00bb en fonction de la DMS. La DOP d\u00e9tient une capacit\u00e9 de pilotage et une visibilit\u00e9 sur l\u2019activit\u00e9 m\u00e9dicale. Toutefois, cette volont\u00e9 d\u2019am\u00e9liorer le fonctionnement des services se heurte \u00e0 des r\u00e9ticences de certains m\u00e9decins. Pour construire un lien, l\u2019accompagnement des m\u00e9decins \u00e0 la r\u00e9organisation de son service est n\u00e9cessaire, ceci permettant \u00e9galement de r\u00e9aliser un contr\u00f4le indirect sur leur activit\u00e9. Nous avons montr\u00e9 comment les \u00e9changes entre acteurs administratifs et m\u00e9decins entra\u00eenent des changements et \u0153uvrent conjointement dans une recherche d\u2019efficience : l\u2019objectif est de poursuivre et afficher une conformit\u00e9 aux indicateurs de DMS et ainsi de r\u00e9duire le surplus de co\u00fbts. Par exemple, on note une modification des protocoles de soins. La d\u00e9cision des gestionnaires de se focaliser sur des indicateurs d\u2019autres \u00e9tablissements contribue \u00e0 renforcer la l\u00e9gitimit\u00e9 du chiffre ainsi que de faciliter l\u2019adh\u00e9sion des praticiens. D\u2019un point de vue gestionnaire, les administratifs per\u00e7oivent l\u2019activit\u00e9 m\u00e9dicale comme une ressource primordiale pour s\u00e9curiser et assurer le fonctionnement de l\u2019\u00e9tablissement. N\u00e9anmoins, la contrepartie de cette s\u00e9curit\u00e9 se caract\u00e9rise par l\u2019obligation de respecter les ratios et ainsi de r\u00e9duire le <em>slack <\/em>organisationnel au sein des services m\u00e9dicaux. Compte-tenu de ces indicateurs, la conformit\u00e9 \u00e0 ces ratios devient une priorit\u00e9 pour l\u2019organisation : l\u2019objectif des gestionnaires est d\u2019am\u00e9liorer les chiffres du CHU en optimisant la prise en charge et en rendant l\u2019activit\u00e9 m\u00e9dicale \u00ab moyenne \u00bb. L\u2019attention de la DOP est focalis\u00e9e sur le respect de ces indicateurs, et souhaite que l\u2019organisation affiche les m\u00eames ratios. Pour cela, soit la DOP accompagne au changement pour r\u00e9duire le <em>slack<\/em>, soit le service clinique se r\u00e9organise de mani\u00e8re autonome.<\/p>\n<p style=\"text-align: justify;\">Nos r\u00e9sultats indiquent que l\u2019<em>accountability <\/em>s\u2019infiltre dans la sph\u00e8re m\u00e9dicale \u00e0 travers des cellules administratives sp\u00e9cifiques et cr\u00e9e un \u00ab climat d\u2019<em>accountability <\/em>\u00bb ayant une influence sur l\u2019hybridation des m\u00e9decins aux comp\u00e9tences gestionnaires ainsi que sur leur activit\u00e9 professionnelle laquelle concilie d\u00e9sormais logique manag\u00e9riale et logique m\u00e9dicale. Aussi, cette recherche, bien qu\u2019elle ne puisse pas \u00eatre g\u00e9n\u00e9ralis\u00e9e \u00e0 d\u2019autres \u00e9tablissements, souligne des int\u00e9r\u00eats manag\u00e9riaux forts.<\/p>\n<p style=\"text-align: right;\"><a href=\"http:\/\/observatoire-asap.org\/index.php\/2021\/03\/23\/marlene-barreda\/\">Marlene Barreda<\/a>, <a href=\"http:\/\/observatoire-asap.org\/index.php\/2021\/03\/23\/irene-georgescu\/\">Ir\u00e8ne Georgescu<\/a>, <a href=\"http:\/\/observatoire-asap.org\/index.php\/2020\/02\/14\/francois-grima\/\">Fran\u00e7ois Grima<\/a>, <a href=\"http:\/\/observatoire-asap.org\/index.php\/2021\/03\/23\/gerald-naro\/\">G\u00e9rald Naro<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>R\u00e9f\u00e9rences<\/strong><\/p>\n<p style=\"text-align: justify;\">Burellier, F., &amp; Valette, A. (2011). Garder ou tomber la blouse?. <em>Journal d&#8217;\u00e9conomie m\u00e9dicale<\/em>, <em>29<\/em>(6), 336-345.<\/p>\n<p style=\"text-align: justify;\">Grenier, C., &amp; Bernardini-Perinciolo, J. (2016). Strategic and Enforced Logics Hybridization: An Agency View within French Hospitals and Universities. In Towards a Comparative Institutionalism: Forms, Dynamics and Logics Across the Organizational Fields of Health Care and Higher Education (pp. 109-144). Emerald Group Publishing Limited.<\/p>\n<p style=\"text-align: justify;\">Kurunm\u00e4ki, L. (2004). A hybrid profession\u2014the acquisition of management accounting expertise by medical professionals. <em>Accounting, organizations and society<\/em>, 29(3-4), 327-347.<\/p>\n<p style=\"text-align: justify;\">Kurunmaki, L., Lapsley, I., &amp; Melia, K. (2003). Accountingization v. legitimation: a comparative study of the use of accounting information in intensive care. <em>Management Accounting Research<\/em>, 14(2), 112-139.<\/p>\n<p style=\"text-align: justify;\">Ruiz-Moreno, A., Garcia-Morales, V. J., &amp; Llorens-Montes, F. J. (2008). The moderating effect of organizational slack on the relation between perceptions of support for innovation and organizational climate. <em>Personnel Review<\/em>, <em>37<\/em>(5), 509-525.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les organisations hybrides, tels que les h\u00f4pitaux sont en tension entre logique manag\u00e9riale et m\u00e9dicale. Au cours des derni\u00e8res d\u00e9cennies, le secteur hospitalier a subi des r\u00e9formes importantes de gestion. Les h\u00f4pitaux, en tant que bureaucraties professionnelles, introduisent, sous une pression coercitive, des contr\u00f4les administratifs au niveau du c\u0153ur op\u00e9rationnel (Kurunm\u00e4ki et al., 2003). La &hellip; <\/p>\n","protected":false},"author":1,"featured_media":2818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[60],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/2810"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2810"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/2810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}