{"id":2785,"date":"2021-03-23T09:48:43","date_gmt":"2021-03-23T08:48:43","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=2785"},"modified":"2021-03-23T09:48:43","modified_gmt":"2021-03-23T08:48:43","slug":"entretien-aupres-dalain-rocca-conseiller-a-la-presidence-pour-la-strategie-editoriale-pedagogique-et-de-developpement-international-de-linstitut-national-de-laudiovisuel-ina","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/03\/23\/entretien-aupres-dalain-rocca-conseiller-a-la-presidence-pour-la-strategie-editoriale-pedagogique-et-de-developpement-international-de-linstitut-national-de-laudiovisuel-ina\/","title":{"rendered":"Entretien aupr\u00e8s d&#8217;Alain Rocca, conseiller \u00e0 la Pr\u00e9sidence pour la strat\u00e9gie \u00e9ditoriale, p\u00e9dagogique, et de d\u00e9veloppement international (Institut National de l\u2019Audiovisuel &#8211; INA)"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n<p>Entretien men\u00e9 par <a href=\"http:\/\/observatoire-asap.org\/index.php\/2020\/11\/23\/michel-barabel\/\">Michel Barabel<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Bonjour Alain, pouvez-vous pr\u00e9senter en quelques mots le<\/strong> <strong>Centre de Formation Professionnelle de l\u2019INA?<\/strong><\/p>\n<p style=\"text-align: justify;\">Le Centre de Formation Professionnelle de l\u2019INA accueille aujourd\u2019hui pr\u00e8s de 3000 stagiaires par an, intermittents du spectacle, salari\u00e9s de l\u2019audiovisuel ou d\u2019autre secteurs, particuliers en recherche d\u2019emploi ou en reconversion, d\u00e9sireux de faire \u00e9voluer leurs comp\u00e9tences dans les m\u00e9tiers de l\u2019audiovisuel et des m\u00e9dias num\u00e9riques. Il dispose d\u2019une \u00e9quipe permanente de 22 responsables p\u00e9dagogiques, compl\u00e9t\u00e9e d\u2019une vingtaine de personnes d\u00e9di\u00e9es \u00e0 l\u2019organisation des stages, fait appel \u00e0 une communaut\u00e9 de 250 intervenants externes, et b\u00e9n\u00e9ficie d\u2019un plateau technique ultramoderne de 7000 m2 r\u00e9parti sur deux sites, \u00e0 Bry-sur-Marne et \u00e0 Issy-Les-Moulineaux.<\/p>\n<p style=\"text-align: justify;\">Son offre de formation se r\u00e9partit sur treize fili\u00e8res, qui couvrent une grande partie des m\u00e9tiers de l\u2019audiovisuel et des m\u00e9dias num\u00e9riques, et propose un catalogue qui recense plus de 450 formations possibles.<\/p>\n<p style=\"text-align: justify;\"><strong>Comme tout centre de formation professionnelle, celui de l\u2019INA a d\u00fb s\u2019adapter au contexte de la Covid-19&nbsp;? Quelles ont \u00e9t\u00e9 les actions mises en place&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify;\">Effectivement, lorsqu\u2019arrive le premier confinement le 16 Mars 2020, aucune de nos formations parmi les 450 du catalogue n\u2019est encore 100% d\u00e9mat\u00e9rialis\u00e9e<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>.<\/p>\n<p style=\"text-align: justify;\">Face \u00e0 cette situation in\u00e9dite, nous avons fait en sorte de garder le lien en ligne avec nos stagiaires. Cela nous a amen\u00e9s \u00e0 op\u00e9rer diff\u00e9rents mouvements&nbsp;:<\/p>\n<ul style=\"text-align: justify;\">\n<li>(1) la \u00ab bascule \u00bb de l\u2019ensemble des responsables p\u00e9dagogiques vers l\u2019utilisation quotidienne des outils de r\u00e9union en ligne. Ces outils (majoritairement Zoom ou Teams, ce dernier \u00e9tant privil\u00e9gi\u00e9 par la DSI de l\u2019INA) sont utilis\u00e9s d\u2019abord pour assurer un suivi \u00ab unilat\u00e9ral \u00bb des formations en cours, en appui de la plateforme LMS maison, et bien \u00e9videmment servent \u00e9galement de support \u00e0 l\u2019ensemble du travail collaboratif permettant de g\u00e9rer la continuit\u00e9 op\u00e9rationnelle de l\u2019activit\u00e9. Dans une moindre mesure, nous avons \u00e9galement eu recours \u00e0 plusieurs dispositifs de classes virtuelles.<\/li>\n<\/ul>\n<ul style=\"text-align: justify;\">\n<li>(2) la transformation imm\u00e9diate en \u00ab&nbsp;100% d\u00e9mat\u00e9ralis\u00e9&nbsp;\u00bb, par une demi-douzaine de responsables p\u00e9dagogiques, de plus d\u2019une vingtaine de sessions de formations, en s\u2019appuyant soit sur la plateforme LMS maison soit sur une plateforme \u00ab&nbsp;standard&nbsp;\u00bb<\/li>\n<li>(3) la cr\u00e9ation ex nihilo de modules en ligne gratuits, sans certification ni \u00e9valuation (vid\u00e9os d\u2019acculturation, webinaires, classes virtuelles\u2026). Initi\u00e9e par la direction pour faire participer \u00e0 sa mani\u00e8re le centre de formation professionnelle \u00e0 la contribution de l\u2019INA, en tant qu\u2019entreprise de l\u2019audiovisuel public, la mise \u00e0 disposition gracieuse de contenus audiovisuels \u00ab&nbsp;culturels&nbsp;\u00bb, entendus au sens large a imm\u00e9diatement rencontr\u00e9 l\u2019approbation de nombreux responsables p\u00e9dagogiques. Ce sont ainsi pr\u00e8s de vingt heures d\u2019acculturation aux probl\u00e9matiques de l\u2019audiovisuel qui ont \u00e9t\u00e9 produites et mises en acc\u00e8s libre sur internet par le centre de formation professionnelle. Au point de classer en mai 2020 l\u2019INA sur le podium des meilleures plateformes gratuites de cours et formation en ligne&nbsp;!<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">L\u2019ensemble de ces actions ont pu \u00eatre r\u00e9alis\u00e9es gr\u00e2ce \u00e0 la conjonction d\u2019une mobilisation absolument exceptionnelle de la petite \u00e9quipe du PADLe (notre \u00e9quipe en charge de l\u2019ing\u00e9nierie p\u00e9dagogique digitale), avec la disponibilit\u00e9 et l\u2019engagement de nombreux collaborateurs de l\u2019\u00e9quipe p\u00e9dagogique et administrative du centre de formation professionnelle.<\/p>\n<p style=\"text-align: justify;\">Au-del\u00e0 des r\u00e9ussites op\u00e9rationnelles constat\u00e9es, cette p\u00e9riode a ainsi permis de constater que la grande majorit\u00e9 des collaboratrices et collaborateurs \u00e9taient en capacit\u00e9 de s\u2019approprier les outils de la d\u00e9mat\u00e9rialisation de leur activit\u00e9\u2026 sous r\u00e9serve d\u2019avoir choisi d\u2019\u00eatre les acteurs de cette appropriation&nbsp;!<\/p>\n<p style=\"text-align: justify;\"><strong>Quels enseignements tirez-vous de la situation&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify;\">Peu \u00e0 peu, \u00e0 des rythmes peut-\u00eatre diff\u00e9rents, la direction et les \u00e9quipes du centre formation professionnelle r\u00e9alisent que la situation in\u00e9dite et disruptive impos\u00e9e par la pand\u00e9mie, va avoir des cons\u00e9quences durables sur leur activit\u00e9.<\/p>\n<p style=\"text-align: justify;\">Au-del\u00e0 des consid\u00e9rations g\u00e9n\u00e9ralistes sur le t\u00e9l\u00e9travail ou des modifications de contexte caus\u00e9es par la nouvelle loi \u00ab&nbsp;Avenir&nbsp;\u00bb, ce sont surtout deux points saillants qui sont per\u00e7us en interne sur cette p\u00e9riode comme significatifs du nouvel avenir de la formation professionnelle \u00e0 l\u2019INA&nbsp;:<\/p>\n<p style=\"text-align: justify;\">En premier lieu, la disparition du projet de holding de l\u2019audiovisuel public de l\u2019horizon op\u00e9rationnel. M\u00eame si elle d\u00e9passe le seul p\u00e9rim\u00e8tre de la d\u00e9lin\u00e9arisation, cette disparition a sur ce champ une cons\u00e9quence claire&nbsp;: la trajectoire de d\u00e9mat\u00e9rialisation de l\u2019offre de formation professionnelle redevient de la pleine responsabilit\u00e9 des \u00e9quipes et de la direction du centre. C\u2019est \u00e0 l\u2019INA d\u2019\u00eatre capable, sans attendre une quelconque alliance ou regroupement, de conserver seule son statut de centre de formation de r\u00e9f\u00e9rence et d\u2019activer pour se faire la trajectoire pertinente de d\u00e9mat\u00e9rialisation.<\/p>\n<p style=\"text-align: justify;\">En second lieu la constatation de deux injonctions, aussi majoritaires que paradoxales, en provenance de nos usagers&nbsp;:<\/p>\n<ul>\n<li style=\"text-align: justify;\">les retours qui remontent de nos interlocuteurs au sein de nos entreprises clientes : l\u2019insistance de celles-ci de diminuer la part pr\u00e9sentielle des sessions de formation qu\u2019ils nous commandent, principalement afin de diminuer le temps d\u2019absence de l\u2019entreprise du salari\u00e9 en formation. D\u00e9j\u00e0 pr\u00e9sente avant le confinement, cette pression pour plus de distanciel gagne en intensit\u00e9 d\u00e8s le premier confinement, pour devenir une quasi-constante ;<\/li>\n<li style=\"text-align: justify;\">ceux de nos clients \u00ab particuliers \u00bb, qui \u00e0 l\u2019inverse insistent sur leur fort attachement \u00e0 la dynamique de groupe induite par la part pr\u00e9sentielle de nos formations, et l\u2019importance qu\u2019ils attachent \u00e0 cette dimension dans l\u2019\u00e9valuation de la qualit\u00e9 de nos formations. Ces remont\u00e9es conservent toute leur intensit\u00e9 m\u00eame dans la p\u00e9riode de r\u00e9ouverture du centre dans un environnement sanitaire particuli\u00e8rement contraignant (masques, distanciation, absence de restauration collective\u2026).<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Le fait que vous soyez une entreprise de l\u2019audiovisuel public change-t-il la donne&nbsp;?<\/strong><\/p>\n<p style=\"text-align: justify;\">Force est de constater qu\u2019en tant que salari\u00e9s de l\u2019audiovisuel public, les collaborateurs de l\u2019INA restent de fait mieux prot\u00e9g\u00e9s que beaucoup de leurs concitoyens des cons\u00e9quences \u00e9conomiques les plus graves de la pand\u00e9mie (perte d\u2019emploi et de salaire).<\/p>\n<p style=\"text-align: justify;\">Nonobstant, d\u00e8s le mois de Juillet, une \u00e9vidence s\u2019\u00e9tait cristallis\u00e9e de fa\u00e7on tr\u00e8s majoritaire au sein de l\u2019ensemble des collaboratrices et des collaborateurs : oui il faut acc\u00e9l\u00e9rer la part d\u00e9mat\u00e9rialis\u00e9e de notre offre de formation professionnelle, mais en veillant \u00e0 conserver tout ce qui fait son ADN et en particulier cette excellence qui s\u2019incarne dans un collectif qui \u00e9change en pr\u00e9sentiel autour de dispositifs techniques r\u00e9els.<\/p>\n<p style=\"text-align: justify;\">Bref, en route vers une d\u00e9mat\u00e9rialisation ma\u00eetris\u00e9e capable d\u2019associer le meilleur du pr\u00e9sentiel avec les avantages du distanciel\u2026. On pourrait parler de pr\u00e9sentiel augment\u00e9&nbsp;!<\/p>\n<p style=\"text-align: justify;\">Ce qui \u00e9tait consid\u00e9r\u00e9 avant le premier confinement comme une orientation strat\u00e9gique de la direction, soutenue par une petite partie des responsables p\u00e9dagogiques, et appr\u00e9ci\u00e9e avec m\u00e9fiance, voire contest\u00e9e, par d\u2019autres, est ainsi devenue en l\u2019espace de quelques mois pour l\u2019ensemble des collaborateurs et collaboratrices un chemin que le centre de formation professionnelle ne peut plus ne pas emprunter\u2026<\/p>\n<p style=\"text-align: justify;\"><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> 120 formations du catalogue b\u00e9n\u00e9ficient d\u2019un accompagnement p\u00e9dagogique d\u00e9mat\u00e9rialis\u00e9, surtout constitu\u00e9 par de la mise \u00e0 disposition en ligne de documents,<\/p>\n<p style=\"text-align: justify;\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Entretien men\u00e9 par Michel Barabel Bonjour Alain, pouvez-vous pr\u00e9senter en quelques mots le Centre de Formation Professionnelle de l\u2019INA? Le Centre de Formation Professionnelle de l\u2019INA accueille aujourd\u2019hui pr\u00e8s de 3000 stagiaires par an, intermittents du spectacle, salari\u00e9s de l\u2019audiovisuel ou d\u2019autre secteurs, particuliers en recherche d\u2019emploi ou en reconversion, d\u00e9sireux de faire \u00e9voluer leurs &hellip; <\/p>\n","protected":false},"author":1,"featured_media":2790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[44,60],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/2785"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2785"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/2785\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2785"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2785"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}