{"id":2648,"date":"2021-03-15T21:19:18","date_gmt":"2021-03-15T20:19:18","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=2648"},"modified":"2021-03-15T21:19:18","modified_gmt":"2021-03-15T20:19:18","slug":"christele-assegond","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/03\/15\/christele-assegond\/","title":{"rendered":"Christ\u00e8le Assegond"},"content":{"rendered":"<p style=\"text-align: justify;\">Christ\u00e8le Assegond est <strong>docteure en sociologie et responsable du Centre d\u2019expertise et de Transfert Universitaire<\/strong> <a href=\"#_top\">ETIcS<\/a> \u00e0 l\u2019Universit\u00e9 de Tours.<\/p>\n<p style=\"text-align: justify;\">Elle est par ailleurs c<strong>hercheure associ\u00e9e au sein du laboratoire <a href=\"http:\/\/citeres.univ-tours.fr\/\">CIt\u00e8res<\/a><\/strong>. Ses travaux portent sur les dimensions sociologiques des contextes de transitions \u00e9nerg\u00e9tique et agrologique.<\/p>\n<p style=\"text-align: justify;\">Elle s\u2019int\u00e9resse en particulier au <strong>r\u00f4le de l\u2019information sur les changements de comportement et leurs impact sur les pratiques sociales.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Christ\u00e8le Assegond est docteure en sociologie et responsable du Centre d\u2019expertise et de Transfert Universitaire ETIcS \u00e0 l\u2019Universit\u00e9 de Tours. Elle est par ailleurs chercheure associ\u00e9e au sein du laboratoire CIt\u00e8res. Ses travaux portent sur les dimensions sociologiques des contextes de transitions \u00e9nerg\u00e9tique et agrologique. Elle s\u2019int\u00e9resse en particulier au r\u00f4le de l\u2019information sur les &hellip; <\/p>\n","protected":false},"author":1,"featured_media":2884,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/2648"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2648"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/2648\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2648"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2648"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}