{"id":2177,"date":"2021-02-19T18:47:14","date_gmt":"2021-02-19T17:47:14","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=2177"},"modified":"2021-02-19T18:47:14","modified_gmt":"2021-02-19T17:47:14","slug":"xavier-lecocq","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/02\/19\/xavier-lecocq\/","title":{"rendered":"Xavier Lecocq"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Xavier Lecocq<\/strong> est <strong>Professeur des Universit\u00e9s<\/strong> \u00e0 l\u2019Universit\u00e9 de Lille o\u00f9 il est membre \u00e9lu de<strong> conseil acad\u00e9mique<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Il anime l\u2019\u00e9quipe de recherche en Strat\u00e9gie, Organisation, Innovation et Entrepreneuriat \u00e0 l\u2019IAE, o\u00f9 il est \u00e9galement membre \u00e9lu du<strong> conseil d\u2019administration<\/strong> et membre du<strong> comit\u00e9 de direction<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Xavier est impliqu\u00e9 dans diff\u00e9rents projets de recherche financ\u00e9s par des entreprises, l\u2019Etat ou des collectivit\u00e9s locales.<\/p>\n<p style=\"text-align: justify;\">Ses travaux portent sur les business models et sur les <strong>formes d\u2019organisation collaboratives<\/strong> (partenariats, open source, coop\u00e9ratives, \u00e9cosyst\u00e8mes d\u2019innovation\u2026).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Xavier Lecocq est Professeur des Universit\u00e9s \u00e0 l\u2019Universit\u00e9 de Lille o\u00f9 il est membre \u00e9lu de conseil acad\u00e9mique. Il anime l\u2019\u00e9quipe de recherche en Strat\u00e9gie, Organisation, Innovation et Entrepreneuriat \u00e0 l\u2019IAE, o\u00f9 il est \u00e9galement membre \u00e9lu du conseil d\u2019administration et membre du comit\u00e9 de direction. Xavier est impliqu\u00e9 dans diff\u00e9rents projets de recherche financ\u00e9s &hellip; <\/p>\n","protected":false},"author":1,"featured_media":2178,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/2177"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2177"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/2177\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media\/2178"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}