{"id":215,"date":"2020-02-27T22:32:06","date_gmt":"2020-02-27T21:32:06","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=215"},"modified":"2020-02-27T22:32:06","modified_gmt":"2020-02-27T21:32:06","slug":"jeanne-le-roy","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2020\/02\/27\/jeanne-le-roy\/","title":{"rendered":"Jeanne Le Roy"},"content":{"rendered":"<div style=\"text-align: justify;\"><strong>Jeanne Le Roy<\/strong> est <strong>enseignant-chercheur en psychologie <\/strong>organisationnelle et management \u00e0 l\u2019European Business School, Paris. Elle est dipl\u00f4m\u00e9e d\u2019un doctorat de psychologie \u00e0 l\u2019Universit\u00e9 Paris Ouest Nanterre la D\u00e9fense. A partir du mod\u00e8le des organisations HERO (HEalthy and Resilient Organization) ses travaux s&#8217;int\u00e9ressent \u00e0 la promotion des comportements innovants et adaptatifs dans les domaines de la <strong>sant\u00e9<\/strong>, de l&#8217;<strong>\u00e9thique<\/strong> et de la <strong>cybers\u00e9curit\u00e9<\/strong>.<\/div>\n<div><\/div>\n<div>\n<p>Ses travaux de recherches ont \u00e9t\u00e9 publi\u00e9s dans des revues telles que: <em>Personnel Review, Social Behavior and Personality: an international journal, International Review of Social Psychology, Journal of\u00a0 La Revue des Sciences de Gestion. <\/em><\/p>\n<\/div>\n<div><\/div>\n<div style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jeanne Le Roy est enseignant-chercheur en psychologie organisationnelle et management \u00e0 l\u2019European Business School, Paris. Elle est dipl\u00f4m\u00e9e d\u2019un doctorat de psychologie \u00e0 l\u2019Universit\u00e9 Paris Ouest Nanterre la D\u00e9fense. A partir du mod\u00e8le des organisations HERO (HEalthy and Resilient Organization) ses travaux s&#8217;int\u00e9ressent \u00e0 la promotion des comportements innovants et adaptatifs dans les domaines de &hellip; <\/p>\n","protected":false},"author":1,"featured_media":230,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/215"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=215"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media\/230"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}