{"id":2053,"date":"2021-02-05T16:30:29","date_gmt":"2021-02-05T15:30:29","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=2053"},"modified":"2021-02-05T16:30:29","modified_gmt":"2021-02-05T15:30:29","slug":"entretien-aupres-de-pascal-chatagnon-et-yann-bergot","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2021\/02\/05\/entretien-aupres-de-pascal-chatagnon-et-yann-bergot\/","title":{"rendered":"Entretien aupr\u00e8s de Pascal Chatagnon et Yann Bergot"},"content":{"rendered":"<p style=\"text-align: justify;\">Entretien par <a href=\"http:\/\/observatoire-asap.org\/index.php\/2020\/11\/24\/denis-cristol\/\">Denis Cristol<\/a>, men\u00e9 aupr\u00e8s de Pascal Chatagnon, adjoint au maire en charge de la participation citoyenne, de la vie associative, de la proximit\u00e9 et de la ville apprenante, et de Yann Bergot directeur g\u00e9n\u00e9ral des services d\u2019\u00c9vry-Courcouronnes, lab\u00e9lis\u00e9es \u00ab ville apprenante \u00bb par l\u2019Unesco.<\/p>\n<p style=\"text-align: justify;\"><strong>Bonjour \u00e0 vous deux, comment d\u00e9velopper une ville apprenante ? Pouvez-vous l\u2019illustrer \u00e0 travers le cas du territoire d\u2019\u00c9vry-Ville-Nouvelle.<\/strong><\/p>\n<p style=\"text-align: justify;\">La d\u00e9marche engag\u00e9e prend racine dans l\u2019histoire du territoire d\u2019\u00c9vry-Ville-Nouvelle, ville monde. Depuis de nombreuses ann\u00e9es, la jeunesse et la diversit\u00e9 de sa population ont conduit \u00e0 une tr\u00e8s forte attention aux questions d\u2019\u00e9ducation dans les quartiers et \u00e0 ne rien s\u2019interdire en termes d\u2019exp\u00e9rimentation, comme avec l\u2019approche relative aux \u00ab cit\u00e9s \u00e9ducatives \u00bb men\u00e9e en \u00e9troite collaboration avec l\u2019\u00c9tat et l\u2019\u00c9ducation nationale depuis 2019. \u00catre une ville apprenante, c\u2019est presque une \u00ab philosophie de la ville nouvelle \u00bb.<\/p>\n<p style=\"text-align: justify;\">Plut\u00f4t que d\u2019aborder la diversit\u00e9 de la population comme un poids, il s\u2019agit de construire un levier d\u2019action, de partage d\u2019exp\u00e9rience et d\u2019enrichissement mutuel pour renforcer le sentiment d\u2019appartenance sociale et la citoyennet\u00e9. En 2018, les villes d\u2019\u00c9vry et de Courcouronnes ont engag\u00e9 un processus de cr\u00e9ation de \u00ab commune nouvelle \u00bb. \u00c0 partir de ce moment, les \u00e9changes qui ont eu lieu avec l\u2019\u00c9tat, le rectorat se sont concentr\u00e9s sur la volont\u00e9 de mettre en avant des richesses du territoire pour en augmenter l\u2019attractivit\u00e9 notamment avec les \u00e9tablissements sup\u00e9rieurs, le G\u00e9nopole, l\u2019universit\u00e9 d\u2019\u00c9vry attach\u00e9e \u00e0 Paris-Saclay XIVe , universit\u00e9 au classement de Shangai. La \u00ab couleur \u00bb de la ville apprenante s\u2019est naturellement d\u00e9tach\u00e9e avec l\u2019id\u00e9e de \u00ab culture scientifique comme projet partag\u00e9 \u00bb.<\/p>\n<p style=\"text-align: justify;\">Le processus de maturation \u00e0 la lab\u00e9lisation Unesco a \u00e9t\u00e9 ponctu\u00e9 d\u2019un hackathon pour pr\u00e9parer la candidature. Toute la communaut\u00e9 \u00e9ducative locale, incluant les associations, a pu s\u2019agr\u00e9ger comme le R\u00e9seau r\u00e9ciproque d\u2019\u00e9change des savoirs (RERS), un GIP (groupe d\u2019int\u00e9r\u00eat public) associ\u00e9 \u00e0 des missions de recherches franco-qu\u00e9b\u00e9coises pour progresser et s\u2019enrichir, par exemple avec l\u2019exp\u00e9rimentation d\u00e8s 2011 du dispositif de pr\u00e9vention du d\u00e9crochage scolaire \u00ab Alternative suspension \u00bb et plus globalement agir sur les th\u00e9matiques de \u00ab pers\u00e9v\u00e9rance scolaire \u00bb et de \u00ab r\u00e9ussite \u00e9ducative \u00bb. Un \u00e9lu porte et suit de pr\u00e8s le projet.<\/p>\n<p style=\"text-align: justify;\"><strong>Quelles ont \u00e9t\u00e9 les diff\u00e9rentes initiatives et actions men\u00e9es ?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sur le territoire, il y a des habitudes de travail (culture de la concertation), un r\u00e9seau d\u2019\u00e9quipements et beaucoup de sujets ayant trait \u00e0 la politique de la ville. Il est donc plus facile de mobiliser des acteurs associatifs. Les acteurs tels que le G\u00e9nopole et les grandes \u00e9coles n\u00e9cessitent encore d\u2019\u00eatre apprivois\u00e9s pour apprendre \u00e0 travailler ensemble. Mais cela co\u00efncide \u00e0 un moment o\u00f9 les grandes \u00e9coles ont besoin d\u2019ouvrir leurs murs, d\u2019irriguer la ville et ses habitants et d\u2019\u00eatre pleinement reli\u00e9es aux territoires dans lequel elles sont pour faire valoir la qualit\u00e9 de leur formation et contribuer \u00e0 l\u2019attractivit\u00e9. Lors des rentr\u00e9es universitaires, cela permet de faire le lien entre la qualit\u00e9 des formations offertes et l\u2019offre du territoire pour mener des projets \u00e0 partir de cette dynamique, de nouveaux projets de coop\u00e9ration naissent, comme la r\u00e9ponse en coalition d\u2019acteurs du territoire \u00e0 un challenge lanc\u00e9 par la communaut\u00e9 europ\u00e9enne ICC (ville intelligente). La journ\u00e9e de lancement du label en pr\u00e9sence d\u2019un repr\u00e9sentant de l\u2019Unesco est marqu\u00e9e par l\u2019installation d\u2019une \u00ab microfolie \u00bb qui a pour objectif de promouvoir cette culture scientifique vis\u00e9e par la ville. Il s\u2019agit d\u2019installer une proximit\u00e9 avec les approches scientifiques et de faire d\u00e9couvrir le num\u00e9rique, les potentialit\u00e9s des fab labs, mais \u00e9galement de s\u2019initier \u00e0 la r\u00e9alit\u00e9 virtuelle en lien avec une grande cha\u00eene de t\u00e9l\u00e9vision, d\u2019offrir un espace pour mettre en sc\u00e8ne la science, car la dimension culturelle fait partie de la ville apprenante. Ce temps de lancement et les initiatives qui vont perdurer participent \u00e0 la cr\u00e9ation d\u2019un patrimoine de m\u00e9moire et d\u2019imaginaire pour les temps \u00e0 venir.<\/p>\n<p style=\"text-align: justify;\"><strong>Comment qualifier une telle dynamique ? Pour quels r\u00e9sultats ?<\/strong><\/p>\n<p style=\"text-align: justify;\">La dynamique de ville apprenante enclench\u00e9e est avant tout une fonction d\u2019entra\u00eenement de tout le territoire o\u00f9 chacun peut apporter son propre champ d\u2019activit\u00e9 au bien commun. Une ville apprenante est en effet une ville qui mobilise effectivement ses ressources et tous les acteurs de son territoire pour dynamiser et multiplier les opportunit\u00e9s d\u2019apprendre \u00e0 tout \u00e2ge et valoriser toutes les formes de savoirs.<\/p>\n<p style=\"text-align: justify;\">Dans un territoire avec beaucoup d\u2019initiatives et de richesses, il y a un enjeu de pilotage et d\u2019animation. La production de la candidature a permis de f\u00e9d\u00e9rer de nombreux acteurs d\u2019horizons diff\u00e9rents, propices \u00e0 des collaborations fructueuses. Elle a aussi contribu\u00e9 \u00e0 inscrire durablement la concertation dans les modes de faire, et permis de construire une base identitaire commune.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entretien par Denis Cristol, men\u00e9 aupr\u00e8s de Pascal Chatagnon, adjoint au maire en charge de la participation citoyenne, de la vie associative, de la proximit\u00e9 et de la ville apprenante, et de Yann Bergot directeur g\u00e9n\u00e9ral des services d\u2019\u00c9vry-Courcouronnes, lab\u00e9lis\u00e9es \u00ab ville apprenante \u00bb par l\u2019Unesco. Bonjour \u00e0 vous deux, comment d\u00e9velopper une ville apprenante &hellip; <\/p>\n","protected":false},"author":1,"featured_media":2062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[71],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/2053"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2053"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/2053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media\/2062"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}