{"id":20,"date":"2020-02-14T15:31:27","date_gmt":"2020-02-14T14:31:27","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=20"},"modified":"2020-02-14T15:31:27","modified_gmt":"2020-02-14T14:31:27","slug":"lexcellence-educative-en-finlande-de-mihaela-vioricat-rusitoru-edition-lharmattan-2019","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2020\/02\/14\/lexcellence-educative-en-finlande-de-mihaela-vioricat-rusitoru-edition-lharmattan-2019\/","title":{"rendered":"L\u2019excellence \u00e9ducative en Finlande de Mihaela-Vioricat Rusitoru &#8211; Edition l\u2019Harmattan 2019"},"content":{"rendered":"<p style=\"text-align: justify;\">Ce petit pays de l\u2019Europe du nord a cr\u00e9\u00e9 la surprise au d\u00e9but des ann\u00e9es 2000\u00a0: Les \u00e9valuations organis\u00e9es par l\u2019OCDE r\u00e9v\u00e8lent sa capacit\u00e9 \u00e0 faire r\u00e9ussir les \u00e9l\u00e8ves tout en luttant contre les in\u00e9galit\u00e9s scolaires. Chercheuse associ\u00e9e \u00e0 l\u2019universit\u00e9 d\u2019Helsinki, l\u2019auteure souhaite informer les acteurs de l\u2019\u00e9ducation et rendre compte de ses observations sur l\u2019organisation de la formation. Ne disposant pas de ressources naturelles, la Finlande a d\u00e9cid\u00e9 de fonder son d\u00e9veloppement sur l\u2019\u00e9ducation et l\u2019innovation. Elle offre \u00e0 tous, quel que soit son \u00e2ge, la possibilit\u00e9 de se former. Pour le syst\u00e8me scolaire, trois principes sont \u00e0 retenir\u00a0: confiance r\u00e9ciproque, \u00e9quit\u00e9 et autonomie des \u00e9quipes p\u00e9dagogiques.<\/p>\n<p style=\"text-align: justify;\">Dans les ann\u00e9es 90, le choix a \u00e9t\u00e9 fait de fonder les relations au sein de l\u2019organisation scolaire sur la confiance r\u00e9ciproque. Cela a entrain\u00e9 la suppression des corps d\u2019inspection et des \u00e9valuations nationales des \u00e9l\u00e8ves \u00e0 l\u2019exception du baccalaur\u00e9at. Pour assurer l\u2019\u00e9quit\u00e9, toutes les d\u00e9penses relatives \u00e0 l\u2019\u00e9ducation (manuels, repas, transport, soins) sont gratuites et les \u00e9l\u00e8ves en difficult\u00e9 peuvent b\u00e9n\u00e9ficier d\u2019un accompagnement individualis\u00e9.<\/p>\n<p style=\"text-align: justify;\">S\u2019il existe bien un curriculum national, les \u00e9quipes p\u00e9dagogiques disposent d\u2019une grande latitude pour adapter les contenus, choisir leurs m\u00e9thodes p\u00e9dagogiques et d\u00e9finir les modalit\u00e9s des \u00e9valuations. Les enseignants sont fortement valoris\u00e9s. Leur formation, directement en lien avec la recherche, leur permet d\u2019adapter constamment leur activit\u00e9 d\u2019enseignement, qui est majoritairement centr\u00e9e sur l\u2019\u00e9l\u00e8ve et ses apprentissages.<\/p>\n<p style=\"text-align: justify;\">Ce mod\u00e8le peut-il inspirer la France dans ses tentatives de r\u00e9former un syst\u00e8me scolaire en souffrance\u00a0? Si l\u2019auteure ne r\u00e9pond pas directement \u00e0 cette question, elle nous donne les \u00e9l\u00e9ments pour aborder la controverse.<\/p>\n<p style=\"text-align: right;\"><a href=\"http:\/\/observatoire-asap.org\/index.php\/2020\/02\/15\/maryvonne-dussaux\/\">Maryvonne Dussaux<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce petit pays de l\u2019Europe du nord a cr\u00e9\u00e9 la surprise au d\u00e9but des ann\u00e9es 2000\u00a0: Les \u00e9valuations organis\u00e9es par l\u2019OCDE r\u00e9v\u00e8lent sa capacit\u00e9 \u00e0 faire r\u00e9ussir les \u00e9l\u00e8ves tout en luttant contre les in\u00e9galit\u00e9s scolaires. Chercheuse associ\u00e9e \u00e0 l\u2019universit\u00e9 d\u2019Helsinki, l\u2019auteure souhaite informer les acteurs de l\u2019\u00e9ducation et rendre compte de ses observations sur &hellip; <\/p>\n","protected":false},"author":1,"featured_media":123,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[40,47,48,55,66],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/20"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=20"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/20\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media\/123"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=20"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=20"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}