{"id":1629,"date":"2020-12-21T10:56:15","date_gmt":"2020-12-21T09:56:15","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=1629"},"modified":"2020-12-21T10:56:15","modified_gmt":"2020-12-21T09:56:15","slug":"erwan-poiraud","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2020\/12\/21\/erwan-poiraud\/","title":{"rendered":"Erwan Poiraud"},"content":{"rendered":"<p style=\"text-align: justify;\">Dipl\u00f4m\u00e9 d\u2019Economie et de Sciences Politiques, <strong>Erwan Poiraud<\/strong> a d\u2019abord exerc\u00e9 son activit\u00e9 professionnelle en tant qu\u2019enseignant titulaire en Lyc\u00e9e et Classes pr\u00e9paratoires aux grandes Ecoles de 1996 \u00e0 2007. Impliqu\u00e9 dans des \u00e9tablissements d\u2019\u00e9ducation en zone prioritaire, il a \u00e9t\u00e9 \u00e0 l\u2019origine de la <strong>cr\u00e9ation d\u2019une Classe Pr\u00e9pa Sciences Po<\/strong> au Lyc\u00e9e Andr\u00e9 Boulloche de Livry-Gargan.<\/p>\n<p style=\"text-align: justify;\">Charg\u00e9 d&#8217;enseignement dans des \u00e9tablissements d\u2019enseignement sup\u00e9rieur priv\u00e9 et \u00e0 l\u2019Universit\u00e9 de Paris-Nanterre, Erwan Poiraud a publi\u00e9 de nombreux articles dans des ouvrages de sciences sociales, \u00e0 la fois sur le r\u00f4le des intellectuels en politique, le d\u00e9cryptage du r\u00f4le du sport dans la soci\u00e9t\u00e9, et sur les <strong>enjeux de l\u2019apprentissage dans la formation<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Depuis 2008, il a \u00e9t\u00e9 successivement <strong>Directeur p\u00e9dagogique<\/strong> au sein du Groupe IGS (Institut de Gestion Sociale), puis <strong>Directeur de Centres de Formation d\u2019Apprentis<\/strong> (CFA) sp\u00e9cialis\u00e9s dans les fonctions du secteur tertiaire. Depuis 2017, il est <strong>Directeur de PPA Business School<\/strong>, une des plus importantes \u00e9coles 100% en alternance en France. Constitu\u00e9e de pr\u00e8s de 4000 alternants, PPA a d\u00e9velopp\u00e9 un centre de recherche afin de proposer une r\u00e9flexion sur l\u2019\u00e9volution des m\u00e9tiers du commerce, de la communication, du marketing, ou encore de la finance. Cette recherche a aussi centr\u00e9 ses travaux sur <strong>l\u2019innovation p\u00e9dagogique<\/strong> li\u00e9e \u00e0 la r\u00e9volution num\u00e9rique en cours, ainsi que sur les enjeux du d\u00e9veloppement de l\u2019alternance dans le cadre des diff\u00e9rentes r\u00e9formes de la formation professionnelle depuis 10 ans.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dipl\u00f4m\u00e9 d\u2019Economie et de Sciences Politiques, Erwan Poiraud a d\u2019abord exerc\u00e9 son activit\u00e9 professionnelle en tant qu\u2019enseignant titulaire en Lyc\u00e9e et Classes pr\u00e9paratoires aux grandes Ecoles de 1996 \u00e0 2007. Impliqu\u00e9 dans des \u00e9tablissements d\u2019\u00e9ducation en zone prioritaire, il a \u00e9t\u00e9 \u00e0 l\u2019origine de la cr\u00e9ation d\u2019une Classe Pr\u00e9pa Sciences Po au Lyc\u00e9e Andr\u00e9 Boulloche &hellip; <\/p>\n","protected":false},"author":1,"featured_media":1630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/1629"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1629"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/1629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media\/1630"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}