{"id":1041,"date":"2020-11-25T18:41:40","date_gmt":"2020-11-25T17:41:40","guid":{"rendered":"http:\/\/observatoire-asap.org\/?p=1041"},"modified":"2020-11-25T18:41:40","modified_gmt":"2020-11-25T17:41:40","slug":"marin-lagny","status":"publish","type":"post","link":"https:\/\/asap.dever.fr\/index.php\/2020\/11\/25\/marin-lagny\/","title":{"rendered":"Marin Lagny"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Marin Lagny<\/strong> est <strong>r\u00e9dacteur en chef<\/strong> de la revue\u00a0 de l&#8217;association les M\u00e9diations Philosophiques &#8220;le M\u00e9diaphi&#8221;, dont l\u2019objectif est d\u2019\u00e9clairer les enjeux des mutations socio-politiques actuelles par le prisme de la philosophie.<\/p>\n<p style=\"text-align: justify;\">Il dirigeait auparavant le journal de sciences humaines et sociales &#8220;La Lanterne&#8221;.<\/p>\n<p style=\"text-align: justify;\">Dans le cadre de ses recherches, il s\u2019int\u00e9resse aux visages contemporains du cosmopolitisme, et notamment aux <strong>d\u00e9fis politico-\u00e9cologiques de l\u2019action publique et soci\u00e9tale<\/strong> que les th\u00e9ories cosmopolitiques permettraient de relever.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marin Lagny est r\u00e9dacteur en chef de la revue\u00a0 de l&#8217;association les M\u00e9diations Philosophiques &#8220;le M\u00e9diaphi&#8221;, dont l\u2019objectif est d\u2019\u00e9clairer les enjeux des mutations socio-politiques actuelles par le prisme de la philosophie. Il dirigeait auparavant le journal de sciences humaines et sociales &#8220;La Lanterne&#8221;. Dans le cadre de ses recherches, il s\u2019int\u00e9resse aux visages contemporains &hellip; <\/p>\n","protected":false},"author":1,"featured_media":1042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/1041"}],"collection":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1041"}],"version-history":[{"count":0,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/posts\/1041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media\/1042"}],"wp:attachment":[{"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asap.dever.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}